{"id":3457,"date":"2023-03-13T15:03:42","date_gmt":"2023-03-13T08:03:42","guid":{"rendered":"https:\/\/www.spu.ac.th\/liberal-arts\/?p=3457"},"modified":"2024-07-08T16:52:34","modified_gmt":"2024-07-08T09:52:34","slug":"%e0%b8%aa%e0%b8%ad%e0%b8%99-japanese-%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%a3%e0%b8%b4%e0%b8%87-%e0%b9%80%e0%b8%81%e0%b9%88%e0%b8%87%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2","status":"publish","type":"post","link":"https:\/\/www.spu.ac.th\/showcase\/%e0%b8%aa%e0%b8%ad%e0%b8%99-japanese-%e0%b9%81%e0%b8%9a%e0%b8%9a%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b8%88%e0%b8%a3%e0%b8%b4%e0%b8%87-%e0%b9%80%e0%b8%81%e0%b9%88%e0%b8%87%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2\/","title":{"rendered":"\u0e2a\u0e2d\u0e19 Japanese \u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e40\u0e01\u0e48\u0e07\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01 \u0e01\u0e31\u0e1a \u0e2d.\u0e42\u0e21\u0e23\u0e34"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3457\" class=\"elementor elementor-3457\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f8d2b0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f8d2b0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-80e67d4\" data-id=\"80e67d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb28402 elementor-widget-divider--separator-type-pattern elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"fb28402\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;3&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpolyline points=&#039;0,18 12,6 24,18 &#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-194f6c9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"194f6c9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8110d46\" data-id=\"8110d46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-711a75d elementor-widget elementor-widget-heading\" data-id=\"711a75d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e2d\u0e19 Japanese \u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e40\u0e01\u0e48\u0e07\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01 \u0e01\u0e31\u0e1a \u0e2d.\u0e42\u0e21\u0e23\u0e34\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-173c602 elementor-widget elementor-widget-text-editor\" data-id=\"173c602\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e14\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e49\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e21\u0e35\u0e19\u0e49\u0e2d\u0e07\u0e46 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e41\u0e07\u0e48\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e20\u0e32\u0e29\u0e32 \u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e2d\u0e35\u0e01\u0e14\u0e49\u0e27\u0e22 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e1e\u0e35\u0e48\u0e41\u0e2d\u0e14\u0e21\u0e34\u0e19\u0e08\u0e36\u0e07\u0e1e\u0e32 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e22\u0e32\u0e2a\u0e38\u0e21\u0e32\u0e2a\u0e32 \u0e42\u0e21\u0e23\u0e34 \u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e19\u0e31\u0e48\u0e07\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e2a\u0e1a\u0e32\u0e22\u0e46 \u0e2a\u0e44\u0e15\u0e25\u0e4c\u0e40\u0e08\u0e41\u0e1b\u0e19 \u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e19\u0e43\u0e08\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e35\u0e1d\u0e31\u0e19\u0e2d\u0e22\u0e32\u0e01\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e01\u0e47\u0e21\u0e32\u0e1f\u0e31\u0e07\u0e1a\u0e17\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e19\u0e35\u0e49\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e08\u0e49\u0e32<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0029ccf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0029ccf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b1d9b3b\" data-id=\"b1d9b3b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2296d7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2296d7c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-248054e\" data-id=\"248054e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3204ae6 elementor-widget elementor-widget-heading\" data-id=\"3204ae6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e42\u0e21\u0e23\u0e34 \u0e1c\u0e39\u0e49\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e40\u0e14\u0e47\u0e01\u0e46<\/br>\n\n\u0e1e\u0e39\u0e14  \u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19  \u0e43\u0e2b\u0e49\u0e40\u0e01\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e593d1 elementor-widget elementor-widget-text-editor\" data-id=\"9e593d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e35\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e17\u0e38\u0e01\u0e04\u0e19\u0e04\u0e23\u0e31\u0e1a \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e0a\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e2a\u0e38\u0e21\u0e32\u0e2a\u0e32 \u0e42\u0e21\u0e23\u0e34 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e21\u0e32\u0e19\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 29 \u0e1b\u0e35\u0e44\u0e14\u0e49\u0e41\u0e25\u0e49\u0e27\u0e41\u0e25\u0e30\u0e17\u0e33\u0e07\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e17\u0e35\u0e48 \u0e21.\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e21\u0e32 26 \u0e1b\u0e35\u0e41\u0e25\u0e49\u0e27 \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e1d\u0e36\u0e01\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1f\u0e31\u0e07\u0e02\u0e48\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e08\u0e32\u0e01 Nation TV \u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21\u0e04\u0e23\u0e31\u0e1a \u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e44\u0e21\u0e48\u0e40\u0e01\u0e48\u0e07\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22\u0e21\u0e32\u0e01 \u0e41\u0e15\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e08\u0e30\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e01\u0e48\u0e07\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e40\u0e01\u0e48\u0e07\u0e20\u0e32\u0e29\u0e32\u0e44\u0e17\u0e22 \u0e41\u0e25\u0e30\u0e2b\u0e27\u0e31\u0e07\u0e27\u0e48\u0e32\u0e17\u0e38\u0e01\u0e04\u0e19\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19\u0e04\u0e23\u0e31\u0e1a<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b63c48b\" data-id=\"b63c48b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5ab0832 elementor-widget elementor-widget-image\" data-id=\"5ab0832\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806124113-683x1024.jpg\" class=\"attachment-large size-large wp-image-3460\" alt=\"\" srcset=\"https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806124113-683x1024.jpg 683w, https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806124113-200x300.jpg 200w, https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806124113-768x1152.jpg 768w, https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806124113.jpg 800w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aba16bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aba16bc\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9ed60e5\" data-id=\"9ed60e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0773f5f elementor-widget elementor-widget-heading\" data-id=\"0773f5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"> \u0e19\u0e32\u0e42\u0e01\u0e22\u0e48\u0e32 \u0e21\u0e35\u0e2d\u0e30\u0e44\u0e23\u0e19\u0e48\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e19\u0e30 ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e1f068 elementor-widget elementor-widget-text-editor\" data-id=\"1e1f068\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e1c\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e19\u0e32\u0e42\u0e01\u0e22\u0e48\u0e32\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e0d\u0e48\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 3 \u0e02\u0e2d\u0e07\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e21\u0e35\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e49\u0e32\u0e21\u0e1e\u0e25\u0e32\u0e14\u0e04\u0e37\u0e2d \u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e19\u0e32\u0e42\u0e01\u0e22\u0e48\u0e32 \u0e2a\u0e27\u0e19\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e42\u0e17\u0e04\u0e38\u0e01\u0e30\u0e27\u0e30 \u0e22\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e42\u0e2d\u0e2a\u0e38 \u0e2b\u0e2d\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e42\u0e17\u0e23\u0e17\u0e31\u0e28\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e21\u0e35\u0e02\u0e2d\u0e07\u0e01\u0e34\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e49\u0e32\u0e21\u0e1e\u0e25\u0e32\u0e14\u0e04\u0e37\u0e2d \u0e40\u0e2a\u0e49\u0e19\u0e1a\u0e30\u0e2b\u0e21\u0e35\u0e48\u0e41\u0e1a\u0e19 \u0e02\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e1b\u0e25\u0e32\u0e44\u0e2b\u0e25 \u0e41\u0e25\u0e30\u0e1b\u0e35\u0e01\u0e44\u0e01\u0e48\u0e17\u0e2d\u0e14\u0e04\u0e23\u0e31\u0e1a \u0e21\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e19\u0e32\u0e42\u0e01\u0e22\u0e48\u0e32\u0e01\u0e31\u0e19\u0e40\u0e22\u0e2d\u0e30\u0e46 \u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2cb2363 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2cb2363\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-552b0e8\" data-id=\"552b0e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63e771d elementor-widget elementor-widget-image\" data-id=\"63e771d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806125354-683x1024.jpg\" class=\"attachment-large size-large wp-image-3462\" alt=\"\" srcset=\"https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806125354-683x1024.jpg 683w, https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806125354-200x300.jpg 200w, https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806125354-768x1152.jpg 768w, https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806125354.jpg 800w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a2496e4\" data-id=\"a2496e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aa9783a elementor-widget elementor-widget-heading\" data-id=\"aa9783a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e44\u0e21\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e23<\/br>\n\u0e02\u0e2d\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e17\u0e31\u0e28\u0e19\u0e04\u0e15\u0e34\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e04\u0e23\u0e31\u0e1a<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2df1afa elementor-widget elementor-widget-text-editor\" data-id=\"2df1afa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e2b\u0e32\u0e01\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e2d\u0e22\u0e32\u0e01\u0e21\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e43\u0e2b\u0e49\u0e21\u0e32\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e23\u0e35\u0e22\u0e19\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e14\u0e35 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e23\u0e21\u0e35\u0e17\u0e31\u0e28\u0e19\u0e04\u0e15\u0e34\u0e15\u0e48\u0e2d\u0e17\u0e31\u0e49\u0e07 3 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e35\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e04\u0e23\u0e31\u0e1a<\/p><p>1. Self-Management \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e04\u0e37\u0e2d \u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e14\u0e39\u0e41\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e14\u0e39\u0e41\u0e25\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e43\u0e2b\u0e49 \u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e30\u0e1a\u0e1a\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e35<br \/>2. Self check \u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e15\u0e19\u0e40\u0e2d\u0e07<br \/>3. Self control \u0e01\u0e32\u0e23\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e04\u0e37\u0e2d \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2d\u0e14\u0e17\u0e19\u0e15\u0e48\u0e2d\u0e2a\u0e34\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e15\u0e48\u0e2d\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e22\u0e2d\u0e21\u0e41\u0e1e\u0e49 \u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e04\u0e27\u0e32\u0e21\u0e02\u0e35\u0e49\u0e40\u0e01\u0e35\u0e22\u0e08\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49 \u0e41\u0e1a\u0e48\u0e07\u0e40\u0e27\u0e25\u0e32\u0e40\u0e25\u0e48\u0e19\u0e41\u0e25\u0e30\u0e40\u0e23\u0e35\u0e22\u0e19\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49<\/p><p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e35\u0e17\u0e31\u0e28\u0e19\u0e04\u0e15\u0e34\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e44\u0e14\u0e49\u0e14\u0e35\u0e17\u0e31\u0e49\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22 \u0e2b\u0e31\u0e27\u0e43\u0e08\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e01\u0e47\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a8f33d elementor-widget elementor-widget-heading\" data-id=\"2a8f33d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e46 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19  \u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \n <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04a6ece elementor-widget elementor-widget-text-editor\" data-id=\"04a6ece\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e21\u0e35\u0e27\u0e34\u0e18\u0e35\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e07\u0e48\u0e32\u0e22\u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07 \u0e23\u0e39\u0e49\/\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\/ \u0e2d\u0e48\u0e32\u0e19\/ \u0e1f\u0e31\u0e07\/ \u0e40\u0e02\u0e35\u0e22\u0e19\/ \u0e1e\u0e39\u0e14\/\u0e08\u0e14\u0e08\u0e33\/ \u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49 \u0e15\u0e32\u0e21\u0e25\u0e33\u0e14\u0e31\u0e1a\u0e19\u0e35\u0e49 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e40\u0e23\u0e32\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u0e43\u0e2b\u0e49\u0e17\u0e1a\u0e17\u0e27\u0e19\u0e2d\u0e35\u0e01\u0e23\u0e2d\u0e1a \u0e41\u0e25\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e32\u0e43\u0e0a\u0e49\u0e20\u0e32\u0e29\u0e32\u0e1c\u0e34\u0e14\u0e01\u0e47\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e49\u0e44\u0e02\u0e08\u0e19\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e17\u0e33\u0e44\u0e14\u0e49 \u0e41\u0e25\u0e30\u0e17\u0e33\u0e0b\u0e49\u0e33\u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e19\u0e40\u0e01\u0e48\u0e07\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e1e\u0e22\u0e32\u0e22\u0e32\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e41\u0e2d\u0e1b\u0e1e\u0e25\u0e34\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e41\u0e1b\u0e25\u0e20\u0e32\u0e29\u0e32\u0e1a\u0e48\u0e2d\u0e22\u0e19\u0e31\u0e01 \u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e14\u0e08\u0e33\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 \u0e15\u0e32 \u0e2b\u0e39 \u0e21\u0e37\u0e2d \u0e41\u0e25\u0e30 \u0e1b\u0e32\u0e01\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e08\u0e30\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e48\u0e07\u0e20\u0e32\u0e29\u0e32\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e44\u0e14\u0e49<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb9cd88 elementor-widget elementor-widget-image\" data-id=\"bb9cd88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"533\" src=\"https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806124939.jpg\" class=\"attachment-large size-large wp-image-3463\" alt=\"\" srcset=\"https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806124939.jpg 800w, https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806124939-300x200.jpg 300w, https:\/\/www.spu.ac.th\/showcase\/wp-content\/uploads\/2023\/03\/20210806124939-768x512.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c160ed2 elementor-widget elementor-widget-heading\" data-id=\"c160ed2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e2d\u0e22\u0e32\u0e01\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1d\u0e36\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e2b\u0e21 ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43c8f3d elementor-widget elementor-widget-text-editor\" data-id=\"43c8f3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e40\u0e23\u0e32\u0e21\u0e35 MOU \u0e01\u0e31\u0e1a\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e14\u0e49\u0e27\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19 6 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e16\u0e36\u0e07 1 \u0e1b\u0e35 \u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e48\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e38\u0e48\u0e19\u0e1e\u0e35\u0e48\u0e17\u0e35\u0e48\u0e44\u0e1b\u0e25\u0e48\u0e32\u0e2a\u0e38\u0e14\u0e04\u0e37\u0e2d\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 Sugiyama Jogakuen University \u0e04\u0e23\u0e31\u0e1a \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e08\u0e30\u0e44\u0e1b\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e15\u0e2d\u0e19\u0e1b\u0e35\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e44\u0e1b\u0e15\u0e2d\u0e19\u0e1b\u0e35 4 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e01\u0e47\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e04\u0e23\u0e1a\u0e08\u0e30\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 \u0e42\u0e14\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e1d\u0e36\u0e01\u0e07\u0e32\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3cbb99 elementor-widget elementor-widget-heading\" data-id=\"e3cbb99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e2d\u0e22\u0e32\u0e01\u0e1d\u0e32\u0e01\u0e16\u0e36\u0e07\u0e17\u0e38\u0e01\u0e04\u0e19\u0e04\u0e23\u0e31\u0e1a<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34abe40 elementor-widget elementor-widget-text-editor\" data-id=\"34abe40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e1c\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e1d\u0e32\u0e01\u0e04\u0e33\u0e04\u0e21\u0e19\u0e35\u0e49\u0e44\u0e27\u0e49\u0e04\u0e23\u0e31\u0e1a<br \/><span style=\"font-size: 14pt;\">\u81ea\u5206\u3092\u5909\u3048\u308b\u3053\u3068\u3067\u3001\u81ea\u5206\u306e\u5c06\u6765\u304c\u5909\u308f\u308b\u3001\u305d\u3057\u3066\u3001\u5168\u3066\u304c\u5909\u3048\u3089\u308c\u308b\u3002<\/span><br \/>\u0e04\u0e37\u0e2d \u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32\u0e19\u0e35\u0e48\u0e41\u0e2b\u0e25\u0e30\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e17\u0e38\u0e01\u0e2a\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a \u0e2a\u0e48\u0e27\u0e19\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e43\u0e08\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e2b\u0e23\u0e37\u0e2d\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19 \u0e16\u0e49\u0e32\u0e0a\u0e2d\u0e1a\u0e01\u0e47\u0e21\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48 \u0e21.\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e22\u0e32\u0e01\u0e44\u0e14\u0e49\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e01\u0e47\u0e21\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e44\u0e14\u0e49<\/p><p>\u0e2a\u0e19\u0e43\u0e08\u0e2d\u0e22\u0e32\u0e01\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1e\u0e27\u0e01\u0e40\u0e23\u0e32\u0e17\u0e35\u0e48 https:\/\/www.facebook.com\/spu.japanese\/<\/p><p>JBC is Journey to the Best Career in the future<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e2d\u0e19 Japanese \u0e41\u0e1a\u0e1a\u0e23\u0e39\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e40\u0e01\u0e48\u0e07\u0e20\u0e32\u0e29\u0e32\u0e0d\u0e35\u0e48\u0e1b\u0e38\u0e48\u0e19\u0e44\u0e21\u0e48\u0e22\u0e32\u0e01 \u0e01\u0e31\u0e1a \u0e2d.\u0e42\u0e21\u0e23 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3458,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[42,7,32,33,43,44,45,36],"class_list":["post-3457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-56","tag-showcase","tag-spu","tag-sripatumuniversity","tag-33","tag-43","tag-44","tag-45","tag-36"],"_links":{"self":[{"href":"https:\/\/www.spu.ac.th\/showcase\/wp-json\/wp\/v2\/posts\/3457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spu.ac.th\/showcase\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spu.ac.th\/showcase\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/showcase\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/showcase\/wp-json\/wp\/v2\/comments?post=3457"}],"version-history":[{"count":0,"href":"https:\/\/www.spu.ac.th\/showcase\/wp-json\/wp\/v2\/posts\/3457\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/showcase\/wp-json\/wp\/v2\/media\/3458"}],"wp:attachment":[{"href":"https:\/\/www.spu.ac.th\/showcase\/wp-json\/wp\/v2\/media?parent=3457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spu.ac.th\/showcase\/wp-json\/wp\/v2\/categories?post=3457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spu.ac.th\/showcase\/wp-json\/wp\/v2\/tags?post=3457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}