{"id":92416,"date":"2026-03-09T14:29:45","date_gmt":"2026-03-09T07:29:45","guid":{"rendered":"https:\/\/www.spu.ac.th\/newsupdate\/?p=92416"},"modified":"2026-03-09T14:29:47","modified_gmt":"2026-03-09T07:29:47","slug":"%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%94%e0%b8%b4%e0%b8%88%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a5%e0%b8%a1%e0%b8%b5%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2-spu-%e0%b8%8a%e0%b8%a7%e0%b8%99-dekspu-%e0%b8%94","status":"publish","type":"post","link":"https:\/\/www.spu.ac.th\/newsupdate\/%e0%b8%84%e0%b8%93%e0%b8%b0%e0%b8%94%e0%b8%b4%e0%b8%88%e0%b8%b4%e0%b8%97%e0%b8%b1%e0%b8%a5%e0%b8%a1%e0%b8%b5%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2-spu-%e0%b8%8a%e0%b8%a7%e0%b8%99-dekspu-%e0%b8%94\/","title":{"rendered":"\u0e04\u0e13\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 SPU \u0e0a\u0e27\u0e19 DEKSPU \u0e14\u0e27\u0e25\u0e28\u0e36\u0e01 VALORANT \u0e43\u0e19\u0e40\u0e27\u0e17\u0e35 \u201cSripatum Esports Festival 2026\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e04\u0e13\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e2a\u0e32\u0e02\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f\u0e41\u0e25\u0e30\u0e40\u0e01\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e27\u0e17\u0e35\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e2a\u0e38\u0e14\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u201cSripatum Esports Festival 2026\u201d \u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19 DEKSPU \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 VALORANT \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcc5\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 7 &#8211; 20 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569<br>(\u0e17\u0e32\u0e07\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19)<br>\ud83d\udcbb\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23 : <a href=\"https:\/\/forms.gle\/w8FMTxG7NBNCew2Y8\" target=\"_blank\" rel=\"noopener\">https:\/\/forms.gle\/w8FMTxG7NBNCew2Y8<\/a><br>\ud83d\udcdd\u0e01\u0e15\u0e34\u0e01\u0e32\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 : <a href=\"https:\/\/shorturl.asia\/v405x\" target=\"_blank\" rel=\"noopener\">https:\/\/shorturl.asia\/v405x<\/a><br>\ud83d\udcad\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 : <a href=\"https:\/\/discord.gg\/hcB68HAQe\" target=\"_blank\" rel=\"noopener\">https:\/\/discord.gg\/hcB68HAQe<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e32\u0e22\u0e38 18 \u0e1b\u0e35\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e27\u0e21\u0e17\u0e35\u0e21\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e17\u0e35\u0e21\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e1a\u0e32\u0e07\u0e40\u0e02\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 3 \u0e04\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e32\u0e19 Esports \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01 \u0e23\u0e2d\u0e1a Online Qualifiers \u0e23\u0e2d\u0e1a Qualifiers 16 Teams \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 23 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e31\u0e14\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e17\u0e35\u0e21\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e23\u0e2d\u0e1a\u0e25\u0e36\u0e01 \u0e01\u0e48\u0e2d\u0e19\u0e08\u0e30\u0e44\u0e1b\u0e2a\u0e39\u0e48 \u0e23\u0e2d\u0e1a 4 Teams Playoffs \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569 &nbsp;\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e23\u0e2d\u0e1a Offline LIVE SEF OVERSEAS \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 27 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569\u0e43\u0e19\u0e07\u0e32\u0e19 Sripatum Esports Festival 2026 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e20\u0e32\u0e22\u0e43\u0e19\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e2d\u0e32\u0e04\u0e32\u0e23 9 \u0e0a\u0e31\u0e49\u0e19 12 (\u0e42\u0e23\u0e07\u0e22\u0e34\u0e21) \u0e40\u0e23\u0e34\u0e48\u0e21\u0e07\u0e32\u0e19\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e27\u0e25\u0e32 8:30 &#8211; 17:45 \u0e19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> VALORANT (General Tournament)<br>\ud83d\udcc5\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u00a0 1 &#8211; 18 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569<br>\ud83d\udcbb\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23 : <a href=\"https:\/\/forms.gle\/Hoehs9DwKonCsmQU7\" target=\"_blank\" rel=\"noopener\">https:\/\/forms.gle\/Hoehs9DwKonCsmQU7<\/a><br>\ud83d\udcdd\u0e01\u0e15\u0e34\u0e01\u0e32\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 : <a href=\"https:\/\/shorturl.asia\/dBD5m\" target=\"_blank\" rel=\"noopener\">https:\/\/shorturl.asia\/dBD5m<\/a><br>\ud83d\udcad\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 : <a href=\"https:\/\/discord.gg\/hcB68HAQe\" target=\"_blank\" rel=\"noopener\">https:\/\/discord.gg\/hcB68HAQe<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e2b\u0e15\u0e38 : \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a Riot Games \u0e2b\u0e23\u0e37\u0e2d VALORANT Esports<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/03\/\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23-SPU-1024x1024.png.webp\" alt=\"\" class=\"wp-image-92417\" srcset=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/03\/\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23-SPU-1024x1024.png.webp 1024w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/03\/\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23-SPU-300x300.png.webp 300w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/03\/\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23-SPU-150x150.png.webp 150w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/03\/\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23-SPU-768x768.png.webp 768w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/uploads\/2026\/03\/\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23-SPU.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<iframe data-src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2FSripatumEsportClub%2Fposts%2Fpfbid0pN9QvjRhgEWXV11UknjmiVYZ1hGpgJxpxV8qVBuzn75MV6nYPmLgJgpqTimvpypvl&#038;show_text=true&#038;width=500\" width=\"500\" height=\"649\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\"><em>#\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 #SripatumUniversity #SPU #\u0e04\u0e13\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 #\u0e2a\u0e32\u0e02\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f\u0e41\u0e25\u0e30\u0e40\u0e01\u0e21 #\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07 #SchoolOfDigitalMedia #SDM #SEF2026 #SripatumEsportsFestival2026<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e13\u0e30\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25\u0e21\u0e35\u0e40\u0e14\u0e35\u0e22 \u0e2a\u0e32\u0e02\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e34\u0e19\u0e40\u0e17\u0e2d\u0e23\u0e4c\u0e41\u0e2d\u0e04\u0e17\u0e35\u0e1f\u0e41\u0e25\u0e30\u0e40\u0e01\u0e21 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e27\u0e17\u0e35\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15\u0e2a\u0e38\u0e14\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48 \u201cSripatum Esports Festival 2026\u201d \u0e40\u0e0a\u0e34\u0e0d\u0e0a\u0e27\u0e19 DEKSPU \u0e23\u0e48\u0e27\u0e21\u0e1e\u0e34\u0e2a\u0e39\u0e08\u0e19\u0e4c\u0e1d\u0e35\u0e21\u0e37\u0e2d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 VALORANT \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49 \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e01\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e35\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 \ud83d\udcc5\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 7 &#8211; 20 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2569(\u0e17\u0e32\u0e07\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e48\u0e32\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19)\ud83d\udcbb\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23 : https:\/\/forms.gle\/w8FMTxG7NBNCew2Y8\ud83d\udcdd\u0e01\u0e15\u0e34\u0e01\u0e32\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 : https:\/\/shorturl.asia\/v405x\ud83d\udcad\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48 : https:\/\/discord.gg\/hcB68HAQe \u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e32\u0e22\u0e38 18 \u0e1b\u0e35\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e27\u0e21\u0e17\u0e35\u0e21\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e41\u0e15\u0e48\u0e25\u0e30\u0e17\u0e35\u0e21\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e1a\u0e32\u0e07\u0e40\u0e02\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e49\u0e2d\u0e22 3 \u0e04\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e34\u0e14\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e14\u0e49\u0e32\u0e19 Esports \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19\u0e08\u0e30\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01 \u0e23\u0e2d\u0e1a Online Qualifiers \u0e23\u0e2d\u0e1a Qualifiers 16 Teams \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":92418,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[593,594],"tags":[51,585,52,158,644,90,91,694,643],"class_list":["post-92416","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-activity","category-594","tag-spu","tag-sripatum-university","tag-sripatumuniversity","tag-158","tag-644","tag-90","tag-91","tag-694","tag-643"],"_links":{"self":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/posts\/92416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/comments?post=92416"}],"version-history":[{"count":0,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/posts\/92416\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/media\/92418"}],"wp:attachment":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/media?parent=92416"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/categories?post=92416"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/tags?post=92416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}