{"id":88808,"date":"2026-01-27T17:21:49","date_gmt":"2026-01-27T10:21:49","guid":{"rendered":"https:\/\/www.spu.ac.th\/newsupdate\/?p=88808"},"modified":"2026-01-27T17:21:52","modified_gmt":"2026-01-27T10:21:52","slug":"%e0%b8%99%e0%b8%b4%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-spu-%e0%b8%9e%e0%b8%b2%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2","status":"publish","type":"post","link":"https:\/\/www.spu.ac.th\/newsupdate\/%e0%b8%99%e0%b8%b4%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-spu-%e0%b8%9e%e0%b8%b2%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a8%e0%b8%b6%e0%b8%81%e0%b8%a9%e0%b8%b2\/","title":{"rendered":"\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c SPU \u0e1e\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u0e01\u0e27\u0e48\u0e32 350 \u0e0a\u0e21\u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07 \u201cStill On My Mind\u201d \u0e40\u0e15\u0e34\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e08\u0e32\u0e01\u0e40\u0e27\u0e17\u0e35\u0e08\u0e23\u0e34\u0e07"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e04\u0e13\u0e30\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2a\u0e32\u0e02\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e19\u0e2d\u0e01\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1e\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u0e01\u0e27\u0e48\u0e32 350 \u0e04\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07 \u201cStill On My Mind : The Musical\u201d \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32 CPA312 \u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19 \u0e13 \u0e2a\u0e27\u0e19\u0e40\u0e1b\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e27\u0e19\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18-19 \u0e41\u0e25\u0e30 24-25 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2569 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e21\u0e34\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e09\u0e32\u0e01 \u0e41\u0e2a\u0e07 \u0e2a\u0e35 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e32\u0e23\u0e21\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e17\u0e32\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e35\u0e48\u0e07\u0e14\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e17\u0e23\u0e07\u0e1e\u0e25\u0e31\u0e07<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07 \u201cStill On My Mind : The Musical \u2013 \u0e43\u0e19\u0e14\u0e27\u0e07\u0e43\u0e08\u0e19\u0e34\u0e23\u0e31\u0e19\u0e14\u0e23\u0e4c\u201d \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e43\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 \u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e17\u0e40\u0e1e\u0e25\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e35\u0e48\u0e22\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e13\u0e35\u0e15 \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e17\u0e31\u0e1a\u0e43\u0e08\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e0b\u0e32\u0e1a\u0e0b\u0e36\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e41\u0e01\u0e48\u0e1c\u0e39\u0e49\u0e0a\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e36\u0e01\u0e0b\u0e36\u0e49\u0e07<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e02\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e17\u0e35\u0e48\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07 \u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e0b\u0e36\u0e21\u0e0b\u0e31\u0e1a\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"88811\" src=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/618383621_1572167847779384_8025665761276979350_n-1024x1024.jpg.webp\" alt=\"\" class=\"wp-image-88811\" srcset=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/618383621_1572167847779384_8025665761276979350_n-1024x1024.jpg.webp 1024w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/618383621_1572167847779384_8025665761276979350_n-300x300.jpg.webp 300w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/618383621_1572167847779384_8025665761276979350_n-150x150.jpg.webp 150w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/618383621_1572167847779384_8025665761276979350_n-768x768.jpg.webp 768w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/uploads\/2026\/01\/618383621_1572167847779384_8025665761276979350_n.jpg 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"88810\" data-src=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/618732975_1572167937779375_5919979388421320523_n-1024x1024.jpg.webp\" alt=\"\" class=\"wp-image-88810 lazyload\" data-srcset=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/618732975_1572167937779375_5919979388421320523_n-1024x1024.jpg.webp 1024w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/618732975_1572167937779375_5919979388421320523_n-300x300.jpg.webp 300w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/618732975_1572167937779375_5919979388421320523_n-150x150.jpg.webp 150w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/618732975_1572167937779375_5919979388421320523_n-768x768.jpg.webp 768w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/uploads\/2026\/01\/618732975_1572167937779375_5919979388421320523_n.jpg 1080w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"88812\" data-src=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/621719940_1572167907779378_1564064325930704158_n-1024x1024.jpg.webp\" alt=\"\" class=\"wp-image-88812 lazyload\" data-srcset=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/621719940_1572167907779378_1564064325930704158_n-1024x1024.jpg.webp 1024w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/621719940_1572167907779378_1564064325930704158_n-300x300.jpg.webp 300w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/621719940_1572167907779378_1564064325930704158_n-150x150.jpg.webp 150w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/01\/621719940_1572167907779378_1564064325930704158_n-768x768.jpg.webp 768w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/uploads\/2026\/01\/621719940_1572167907779378_1564064325930704158_n.jpg 1080w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/1024;\" \/><\/figure>\n<\/figure>\n\n\n\n<iframe data-src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fspu.performingarts%2Fposts%2Fpfbid0kaPhEGMiTmL25TLBEMWf4cRS9MSTg7hRKB1bpn2RKSdT32Q3wZ5Jud7ZBygG3gHwl&#038;show_text=true&#038;width=500\" width=\"500\" height=\"681\" style=\"border:none;overflow:hidden\" scrolling=\"no\" frameborder=\"0\" allowfullscreen=\"true\" allow=\"autoplay; clipboard-write; encrypted-media; picture-in-picture; web-share\" src=\"about:blank\" class=\"lazyload\" data-load-mode=\"0\"><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\"><em>#\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 #SripatumUniversity #SPU #\u0e04\u0e13\u0e30\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4cSPU #SPU\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07<\/em><em> #CPASPU #\u0e2a\u0e32\u0e02\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e13\u0e30\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e2a\u0e32\u0e02\u0e32\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e19\u0e2d\u0e01\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1e\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 3 \u0e01\u0e27\u0e48\u0e32 350 \u0e04\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07 \u201cStill On My Mind : The Musical\u201d \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32 CPA312 \u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e23\u0e2d\u0e1a\u0e14\u0e49\u0e32\u0e19 \u0e13 \u0e2a\u0e27\u0e19\u0e40\u0e1b\u0e23\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e27\u0e19\u0e32\u0e23\u0e31\u0e01\u0e29\u0e4c \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 18-19 \u0e41\u0e25\u0e30 24-25 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2569 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e21\u0e34\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07 \u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e23\u0e49\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e2b\u0e27 \u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e09\u0e32\u0e01 \u0e41\u0e2a\u0e07 \u0e2a\u0e35 \u0e40\u0e2a\u0e35\u0e22\u0e07 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e32\u0e23\u0e21\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e04\u0e48\u0e32\u0e17\u0e32\u0e07\u0e28\u0e34\u0e25\u0e1b\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e1c\u0e48\u0e32\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e17\u0e35\u0e48\u0e07\u0e14\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e17\u0e23\u0e07\u0e1e\u0e25\u0e31\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e30\u0e04\u0e23\u0e40\u0e1e\u0e25\u0e07 \u201cStill On My Mind : The Musical \u2013 \u0e43\u0e19\u0e14\u0e27\u0e07\u0e43\u0e08\u0e19\u0e34\u0e23\u0e31\u0e19\u0e14\u0e23\u0e4c\u201d \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d \u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e43\u0e19\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e19\u0e32\u0e07\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e23\u0e34\u0e01\u0e34\u0e15\u0e34\u0e4c \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e34\u0e19\u0e35\u0e19\u0e32\u0e16 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e19\u0e35\u0e1e\u0e31\u0e19\u0e1b\u0e35\u0e2b\u0e25\u0e27\u0e07 [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":88814,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[593,595],"tags":[51,585,52,164,644,91,491,643],"class_list":["post-88808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-activity","category-595","tag-spu","tag-sripatum-university","tag-sripatumuniversity","tag-164","tag-644","tag-91","tag-491","tag-643"],"_links":{"self":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/posts\/88808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/comments?post=88808"}],"version-history":[{"count":0,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/posts\/88808\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/media\/88814"}],"wp:attachment":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/media?parent=88808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/categories?post=88808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/tags?post=88808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}