{"id":103142,"date":"2026-07-15T17:13:41","date_gmt":"2026-07-15T10:13:41","guid":{"rendered":"https:\/\/www.spu.ac.th\/newsupdate\/?p=103142"},"modified":"2026-07-15T17:13:43","modified_gmt":"2026-07-15T10:13:43","slug":"%e0%b8%a7%e0%b8%b4%e0%b8%a8%e0%b8%a7%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-spu-tbim-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b9%80%e0%b8%a7","status":"publish","type":"post","link":"https:\/\/www.spu.ac.th\/newsupdate\/%e0%b8%a7%e0%b8%b4%e0%b8%a8%e0%b8%a7%e0%b8%81%e0%b8%a3%e0%b8%a3%e0%b8%a1%e0%b8%a8%e0%b8%b2%e0%b8%aa%e0%b8%95%e0%b8%a3%e0%b9%8c-spu-tbim-%e0%b9%80%e0%b8%9b%e0%b8%b4%e0%b8%94%e0%b9%80%e0%b8%a7\/","title":{"rendered":"\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c SPU\u2013TBIM \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e27\u0e17\u0e35\u0e44\u0e17\u0e22\u2013\u0e08\u0e35\u0e19 \u0e1c\u0e19\u0e36\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 BIM \u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e1a\u0e1a\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (TBIM) \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e27\u0e17\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 <strong>\u201cThailand\u2013China Construction Standards Comparison and Application Research Workshop\u201d<\/strong> \u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e23\u0e32\u0e01\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 14 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2569 \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e27\u0e17\u0e35\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e1a\u0e1b\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e44\u0e17\u0e22\u2013\u0e08\u0e35\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 Building Information Modeling \u0e2b\u0e23\u0e37\u0e2d BIM \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e44\u0e1e\u0e08\u0e34\u0e15\u0e23 \u0e1c\u0e32\u0e27\u0e31\u0e19<\/strong> \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e19\u0e32\u0e22\u0e01\u0e04\u0e19\u0e17\u0e35\u0e48 1 \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e1a\u0e1a\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e44\u0e17\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e27\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e23\u0e48\u0e27\u0e21 \u0e2b\u0e23\u0e37\u0e2d <strong>Collaborative Research Agenda<\/strong> \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e38\u0e48\u0e07\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e27\u0e34\u0e08\u0e31\u0e22\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e21\u0e34\u0e15\u0e34 \u0e2d\u0e32\u0e17\u0e34 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e10\u0e32\u0e19\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1b\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e04\u0e27\u0e32\u0e21\u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d <strong>Resilient Buildings<\/strong> \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e23\u0e48\u0e27\u0e21\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e02\u0e2d\u0e07\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e19\u0e33\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e20\u0e32\u0e22\u0e43\u0e19\u0e07\u0e32\u0e19\u0e21\u0e35\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e08\u0e32\u0e01\u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\u0e49\u0e21\u0e02\u0e49\u0e19 \u0e19\u0e33\u0e42\u0e14\u0e22 <strong>\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e44\u0e1e\u0e1a\u0e39\u0e25\u0e22\u0e4c \u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e04\u0e30\u0e42\u0e1b<\/strong> \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e42\u0e22\u0e18\u0e32 \u0e41\u0e25\u0e30 <strong>\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e27\u0e23\u0e34\u0e2a\u0e23\u0e32 \u0e40\u0e25\u0e34\u0e28\u0e44\u0e1e\u0e11\u0e39\u0e23\u0e22\u0e4c\u0e1e\u0e31\u0e19\u0e18\u0e4c<\/strong> \u0e23\u0e2d\u0e07\u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e2a\u0e21\u0e32\u0e04\u0e21 TBIM \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e1c\u0e39\u0e49\u0e17\u0e23\u0e07\u0e04\u0e38\u0e13\u0e27\u0e38\u0e12\u0e34\u0e08\u0e32\u0e01\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e08\u0e32\u0e01\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 <strong>China Institute of Building Standard Design &amp; Research Co., Ltd., China Academy of Building Research Co., Ltd., China Building Technique Group Co., Ltd. \u0e41\u0e25\u0e30 CCCC Second Highway Consultants Co., Ltd.<\/strong> \u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2a\u0e32\u0e01\u0e25<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07 \u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07\u0e08\u0e32\u0e01\u0e20\u0e32\u0e04\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e25\u0e01 \u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 <strong>Future Skills<\/strong> \u0e17\u0e31\u0e49\u0e07\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 BIM \u0e01\u0e32\u0e23\u0e04\u0e34\u0e14\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e02\u0e49\u0e32\u0e21\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e40\u0e27\u0e17\u0e35 <strong>Thailand\u2013China Construction Standards Comparison and Application Research Workshop<\/strong> \u0e08\u0e36\u0e07\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e25\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 \u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23 <strong>\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19<\/strong> \u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e44\u0e17\u0e22\u2013\u0e08\u0e35\u0e19\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e19\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e2d\u0e21\u0e23\u0e27\u0e21\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e39\u0e48\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e2a\u0e32\u0e01\u0e25 \u0e44\u0e21\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e0a\u0e48\u0e27\u0e22\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e41\u0e15\u0e48\u0e22\u0e31\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d \u0e41\u0e25\u0e30\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 <strong>\u201c\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07 \u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07\u201d<\/strong> \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07 \u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"103145\" src=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/745542129_1051403473981465_3110083614936162340_n-1024x768.jpeg.webp\" alt=\"\" class=\"wp-image-103145\" srcset=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/745542129_1051403473981465_3110083614936162340_n-1024x768.jpeg.webp 1024w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/745542129_1051403473981465_3110083614936162340_n-300x225.jpeg.webp 300w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/745542129_1051403473981465_3110083614936162340_n-768x576.jpeg.webp 768w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/uploads\/2026\/07\/745542129_1051403473981465_3110083614936162340_n.jpeg 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"103144\" data-src=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746129977_1519108026346737_3254613656036827415_n-1024x768.jpeg.webp\" alt=\"\" class=\"wp-image-103144 lazyload\" data-srcset=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746129977_1519108026346737_3254613656036827415_n-1024x768.jpeg.webp 1024w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746129977_1519108026346737_3254613656036827415_n-300x225.jpeg.webp 300w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746129977_1519108026346737_3254613656036827415_n-768x576.jpeg.webp 768w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/uploads\/2026\/07\/746129977_1519108026346737_3254613656036827415_n.jpeg 1477w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"103148\" data-src=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/745542129_1735317744164092_1235641205536045745_n-1024x768.jpeg.webp\" alt=\"\" class=\"wp-image-103148 lazyload\" data-srcset=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/745542129_1735317744164092_1235641205536045745_n-1024x768.jpeg.webp 1024w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/745542129_1735317744164092_1235641205536045745_n-300x225.jpeg.webp 300w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/745542129_1735317744164092_1235641205536045745_n-768x576.jpeg.webp 768w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/uploads\/2026\/07\/745542129_1735317744164092_1235641205536045745_n.jpeg 1477w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"103149\" data-src=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/747062703_1048430771044773_4199482060915483195_n-1024x768.jpeg.webp\" alt=\"\" class=\"wp-image-103149 lazyload\" data-srcset=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/747062703_1048430771044773_4199482060915483195_n-1024x768.jpeg.webp 1024w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/747062703_1048430771044773_4199482060915483195_n-300x225.jpeg.webp 300w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/747062703_1048430771044773_4199482060915483195_n-768x576.jpeg.webp 768w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/uploads\/2026\/07\/747062703_1048430771044773_4199482060915483195_n.jpeg 1477w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"103146\" data-src=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746947194_1332487332431973_427115583353178060_n-1024x768.jpeg.webp\" alt=\"\" class=\"wp-image-103146 lazyload\" data-srcset=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746947194_1332487332431973_427115583353178060_n-1024x768.jpeg.webp 1024w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746947194_1332487332431973_427115583353178060_n-300x225.jpeg.webp 300w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746947194_1332487332431973_427115583353178060_n-768x576.jpeg.webp 768w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/uploads\/2026\/07\/746947194_1332487332431973_427115583353178060_n.jpeg 1477w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"103147\" data-src=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746411711_1450186003799386_4840662052558263979_n-1024x768.jpeg.webp\" alt=\"\" class=\"wp-image-103147 lazyload\" data-srcset=\"https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746411711_1450186003799386_4840662052558263979_n-1024x768.jpeg.webp 1024w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746411711_1450186003799386_4840662052558263979_n-300x225.jpeg.webp 300w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/smush-webp\/2026\/07\/746411711_1450186003799386_4840662052558263979_n-768x576.jpeg.webp 768w, https:\/\/www.spu.ac.th\/newsupdate\/wp-content\/uploads\/2026\/07\/746411711_1450186003799386_4840662052558263979_n.jpeg 1477w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>#SPU #\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 #\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4cSPU #SPUEngineering #TBIM #ThailandChinaWorkshop #\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07 #\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19 #\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e2d\u0e01\u0e32\u0e2a #FutureSkills #BIM #ConstructionStandards #EngineeringResearch #InternationalCollaboration #SDG4 #SDG9 #SDG17<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e1a\u0e1a\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 (TBIM) \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e27\u0e17\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e40\u0e0a\u0e34\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u201cThailand\u2013China Construction Standards Comparison and Application Research Workshop\u201d \u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e32\u0e01\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e27\u0e32\u0e07\u0e23\u0e32\u0e01\u0e10\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2a\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 14 \u0e01\u0e23\u0e01\u0e0e\u0e32\u0e04\u0e21 2569 \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e40\u0e27\u0e17\u0e35\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e1a\u0e1b\u0e30\u0e40\u0e0a\u0e34\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e38\u0e14\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e44\u0e17\u0e22\u2013\u0e08\u0e35\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e48\u0e2d\u0e22\u0e2d\u0e14\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e07\u0e32\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22\u0e14\u0e49\u0e32\u0e19\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 Building Information Modeling \u0e2b\u0e23\u0e37\u0e2d BIM \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e22\u0e37\u0e14\u0e2b\u0e22\u0e38\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e44\u0e1e\u0e08\u0e34\u0e15\u0e23 \u0e1c\u0e32\u0e27\u0e31\u0e19 \u0e04\u0e13\u0e1a\u0e14\u0e35\u0e04\u0e13\u0e30\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e19\u0e32\u0e22\u0e01\u0e04\u0e19\u0e17\u0e35\u0e48 1 \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e41\u0e1a\u0e1a\u0e08\u0e33\u0e25\u0e2d\u0e07\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2d\u0e32\u0e04\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e43\u0e2b\u0e49\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e44\u0e17\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e43\u0e2b\u0e49\u0e21\u0e35\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e17\u0e34\u0e28\u0e17\u0e32\u0e07\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48 \u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21 \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14\u0e27\u0e32\u0e23\u0e30\u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e23\u0e48\u0e27\u0e21 \u0e2b\u0e23\u0e37\u0e2d Collaborative Research Agenda [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":103143,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[593,737,599],"tags":[51,585,644,91,137,643],"class_list":["post-103142","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-activity","category-maincenter","category-599","tag-spu","tag-sripatum-university","tag-644","tag-91","tag-137","tag-643"],"_links":{"self":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/posts\/103142","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/comments?post=103142"}],"version-history":[{"count":1,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/posts\/103142\/revisions"}],"predecessor-version":[{"id":103150,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/posts\/103142\/revisions\/103150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/media\/103143"}],"wp:attachment":[{"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/media?parent=103142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/categories?post=103142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spu.ac.th\/newsupdate\/wp-json\/wp\/v2\/tags?post=103142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}