{"id":174876,"date":"2026-07-15T01:31:29","date_gmt":"2026-07-15T01:31:29","guid":{"rendered":"https:\/\/www.spu.ac.th\/fac\/logistics\/?p=174876"},"modified":"2026-07-15T01:31:33","modified_gmt":"2026-07-15T01:31:33","slug":"usc12067-futurium69","status":"publish","type":"post","link":"https:\/\/www.spu.ac.th\/fac\/logistics\/usc12067-futurium69\/","title":{"rendered":"\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32 USC12067 \u0e17\u0e31\u0e01\u0e29\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e1e\u0e32\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32 DEK69 \u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e42\u0e25\u0e01\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e13 FUTURIUM"},"content":{"rendered":"<p>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 1 (DEK69) \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32 <strong>USC12067 \u0e17\u0e31\u0e01\u0e29\u0e30\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 (Future Skills)<\/strong> \u0e40\u0e02\u0e49\u0e32\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e19\u0e2d\u0e01\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e13 <strong>FUTURIUM<\/strong> \u0e28\u0e39\u0e19\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e34\u0e14\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e39\u0e48\u0e42\u0e25\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07<\/p>\n<p>\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e44\u0e14\u0e49\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e40\u0e0a\u0e34\u0e07\u0e42\u0e15\u0e49\u0e15\u0e2d\u0e1a (Interactive Exhibition) \u0e17\u0e35\u0e48\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e1b\u0e23\u0e30\u0e14\u0e34\u0e29\u0e10\u0e4c (AI) \u0e2b\u0e38\u0e48\u0e19\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2d\u0e27\u0e01\u0e32\u0e28 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2d\u0e31\u0e08\u0e09\u0e23\u0e34\u0e22\u0e30 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e14\u0e33\u0e23\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e28\u0e15\u0e27\u0e23\u0e23\u0e29\u0e17\u0e35\u0e48 21<\/p>\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e1c\u0e48\u0e32\u0e19\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e41\u0e25\u0e49\u0e27 \u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e1d\u0e36\u0e01\u0e15\u0e31\u0e49\u0e07\u0e04\u0e33\u0e16\u0e32\u0e21 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e01\u0e29\u0e30\u0e01\u0e32\u0e23\u0e04\u0e34\u0e14\u0e40\u0e0a\u0e34\u0e07\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e01\u0e32\u0e23\u0e04\u0e34\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e15\u0e31\u0e27 \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48<\/p>\n<p>\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e14\u0e39\u0e07\u0e32\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21\u0e17\u0e35\u0e48\u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e08\u0e32\u0e01\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07 \u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e42\u0e22\u0e07\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e42\u0e25\u0e01\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e17\u0e31\u0e01\u0e29\u0e30 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e2a\u0e31\u0e22\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e02\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35<\/p>\n<p>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21\u0e22\u0e31\u0e07\u0e04\u0e07\u0e21\u0e38\u0e48\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07 <strong>\u0e42\u0e2d\u0e01\u0e32\u0e2a<\/strong> \u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e04\u0e49\u0e19\u0e1e\u0e1a\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e02\u0e2d\u0e07\u0e15\u0e19\u0e40\u0e2d\u0e07 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e08\u0e32\u0e01\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e30\u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e41\u0e19\u0e27\u0e04\u0e34\u0e14 <strong>&#8220;\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07 \u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07&#8221;<\/strong> \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 <strong>Future Skills<\/strong> \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e49\u0e32\u0e27\u0e2a\u0e39\u0e48\u0e42\u0e25\u0e01\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08<\/p>\n<p><strong>#\u0e42\u0e2d\u0e01\u0e32\u0e2a #\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e15\u0e31\u0e27\u0e08\u0e23\u0e34\u0e07 #\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e08\u0e23\u0e34\u0e07 #\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19 #FutureSkills<\/strong><\/p>\n\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"856\" height=\"1024\" data-id=\"174877\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_2-856x1024.jpg.webp\" alt=\"\" class=\"wp-image-174877\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_2-856x1024.jpg.webp 856w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_2-251x300.jpg.webp 251w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_2-768x919.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_2.jpg.webp 960w\" sizes=\"(max-width: 856px) 100vw, 856px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"174880\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_4-768x1024.jpg.webp\" alt=\"\" class=\"wp-image-174880\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_4-768x1024.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_4-225x300.jpg.webp 225w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_4-1152x1536.jpg.webp 1152w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_4.jpg.webp 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174881\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_5-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174881\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_5-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_5-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_5-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_5.jpg.webp 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"174882\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_6-1024x576.jpg.webp\" alt=\"\" class=\"wp-image-174882\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_6-1024x576.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_6-300x169.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_6-768x432.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_6-1536x864.jpg.webp 1536w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_6.jpg.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"174910\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_7-768x1024.jpg.webp\" alt=\"\" class=\"wp-image-174910\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_7-768x1024.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_7-225x300.jpg.webp 225w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_7-1152x1536.jpg.webp 1152w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_7.jpg.webp 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174894\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_8-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174894\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_8-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_8-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_8-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_8.jpg.webp 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174893\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_9-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174893\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_9-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_9-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_9-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_9.jpg.webp 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174895\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_10-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174895\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_10-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_10-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_10-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_10.jpg.webp 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174890\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_11-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174890\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_11-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_11-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_11-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_11.jpg.webp 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174889\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_13-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174889\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_13-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_13-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_13-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_13.jpg.webp 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174913\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_15-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174913\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_15-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_15-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_15-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_15.jpg.webp 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174917\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_16-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174917\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_16-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_16-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_16-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_16.jpg.webp 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174918\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_17-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174918\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_17-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_17-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_17-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_17.jpg.webp 1477w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174925\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_19-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174925\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_19-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_19-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_19-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_19-1536x1152.jpg.webp 1536w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_19.jpg.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174930\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_20-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174930\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_20-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_20-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_20-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_20-1536x1152.jpg.webp 1536w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_20.jpg.webp 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"174915\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_21-768x1024.jpg.webp\" alt=\"\" class=\"wp-image-174915\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_21-768x1024.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_21-225x300.jpg.webp 225w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_21-1152x1536.jpg.webp 1152w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_21.jpg.webp 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"174922\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_22-768x1024.jpg.webp\" alt=\"\" class=\"wp-image-174922\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_22-768x1024.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_22-225x300.jpg.webp 225w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_22-1152x1536.jpg.webp 1152w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_22.jpg.webp 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"174896\" src=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_23-1024x768.jpg.webp\" alt=\"\" class=\"wp-image-174896\" srcset=\"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_23-1024x768.jpg.webp 1024w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_23-300x225.jpg.webp 300w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_23-768x576.jpg.webp 768w, https:\/\/www.spu.ac.th\/fac\/logistics\/wp-content\/smush-webp\/sites\/9\/2026\/07\/LINE_ALBUM_FUTURIUM-DEK69_260715_23.jpg.webp 1206w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e19\u0e33\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e0a\u0e31\u0e49\u0e19\u0e1b\u0e35\u0e17\u0e35\u0e48 1 (DEK69) \u0e43\u0e19\u0e23\u0e32\u0e22\u0e27 [&hellip;]<\/p>\n","protected":false},"author":56,"featured_media":174933,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[452,58],"tags":[33,30,27,28,31],"class_list":["post-174876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quality-education-sdg-4","category-58","tag-logistics","tag-spu","tag-sripatumuniversity","tag-28","tag-31"],"_links":{"self":[{"href":"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-json\/wp\/v2\/posts\/174876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-json\/wp\/v2\/comments?post=174876"}],"version-history":[{"count":0,"href":"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-json\/wp\/v2\/posts\/174876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-json\/wp\/v2\/media\/174933"}],"wp:attachment":[{"href":"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-json\/wp\/v2\/media?parent=174876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-json\/wp\/v2\/categories?post=174876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/logistics\/wp-json\/wp\/v2\/tags?post=174876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}