{"id":300,"date":"2023-02-20T07:57:34","date_gmt":"2023-02-20T07:57:34","guid":{"rendered":"https:\/\/www.spu.ac.th\/liberal-arts\/?page_id=300"},"modified":"2025-02-28T09:33:55","modified_gmt":"2025-02-28T09:33:55","slug":"staff-2","status":"publish","type":"page","link":"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-2\/","title":{"rendered":"\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e19\u0e34\u0e15\u0e34\u0e23\u0e31\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"300\" class=\"elementor elementor-300\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7370ccb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7370ccb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f78daed\" data-id=\"f78daed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d59394a elementor-widget elementor-widget-template\" data-id=\"d59394a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"94\" class=\"elementor elementor-94\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d056a5b elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"6d056a5b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ec76f0c\" data-id=\"3ec76f0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a1906e4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"2a1906e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73c7c6c5\" data-id=\"73c7c6c5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-445fdc76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"445fdc76\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2fd12cac\" data-id=\"2fd12cac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b5cdb0b elementor-widget elementor-widget-heading\" data-id=\"5b5cdb0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e21.\u0e40\u0e2d\u0e01\u0e0a\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e23\u0e01<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43620604 elementor-widget elementor-widget-heading\" data-id=\"43620604\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e2a\u0e2d\u0e19\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-16ea2d39\" data-id=\"16ea2d39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7093438d elementor-widget elementor-widget-heading\" data-id=\"7093438d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e31\u0e19\u0e2a\u0e21\u0e31\u0e22<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f451e68 elementor-widget elementor-widget-heading\" data-id=\"1f451e68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e31\u0e49\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e14\u0e34\u0e08\u0e34\u0e17\u0e31\u0e25 \u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e0b\u0e40\u0e1a\u0e2d\u0e23\u0e4c<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-efaa85a\" data-id=\"efaa85a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24742ad7 elementor-widget elementor-widget-heading\" data-id=\"24742ad7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e7e9d14 elementor-widget elementor-widget-heading\" data-id=\"3e7e9d14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e1c\u0e39\u0e49\u0e1e\u0e34\u0e1e\u0e32\u0e01\u0e29\u0e32 \u0e2d\u0e31\u0e22\u0e01\u0e32\u0e23<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-78ed43f2\" data-id=\"78ed43f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-681f5bbf elementor-widget elementor-widget-heading\" data-id=\"681f5bbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e1b\u0e34\u0e14\u0e2a\u0e2d\u0e19\u0e04\u0e23\u0e1a\u0e08\u0e1a\u0e43\u0e19\u0e17\u0e35\u0e48\u0e40\u0e14\u0e35\u0e22\u0e27<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-627da75 elementor-widget elementor-widget-heading\" data-id=\"627da75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 \u0e42\u0e17 \u0e40\u0e2d\u0e01<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-64942808\" data-id=\"64942808\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25aae35d elementor-widget elementor-widget-heading\" data-id=\"25aae35d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e21\u0e35\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb8cce3 elementor-widget elementor-widget-heading\" data-id=\"3bb8cce3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e1c\u0e39\u0e49\u0e17\u0e33\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e2a\u0e32\u0e23\u0e4c - \u0e2d\u0e32\u0e17\u0e34\u0e15\u0e22\u0e4c<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eeb4297 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eeb4297\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-db5c356\" data-id=\"db5c356\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-983a3b1 elementor-nav-menu__align-end elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"983a3b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-983a3b1\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-386\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/\" class=\"elementor-item\">\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-382\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-1\/\" class=\"elementor-item\">\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-383\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-4\/\" class=\"elementor-item\">\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e21\u0e2b\u0e32\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-384\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-3\/\" class=\"elementor-item\">\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-385\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-2\/\" class=\"elementor-item\">\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e19\u0e34\u0e15\u0e34\u0e23\u0e31\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3789\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-5\/\" class=\"elementor-item\">\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e25\u0e02\u0e32\u0e19\u0e38\u0e01\u0e32\u0e23\u0e04\u0e13\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-16139\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/%e0%b8%ad%e0%b8%b2%e0%b8%88%e0%b8%b2%e0%b8%a3%e0%b8%a2%e0%b9%8c%e0%b8%9e%e0%b8%b4%e0%b9%80%e0%b8%a8%e0%b8%a9\/\" class=\"elementor-item\">\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1e\u0e34\u0e40\u0e28\u0e29<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-983a3b1\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-386\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-382\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-1\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-383\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-4\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e21\u0e2b\u0e32\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-384\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-3\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-385\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-2\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e19\u0e34\u0e15\u0e34\u0e23\u0e31\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-3789\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/staff-5\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e40\u0e25\u0e02\u0e32\u0e19\u0e38\u0e01\u0e32\u0e23\u0e04\u0e13\u0e30\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-16139\"><a href=\"https:\/\/www.spu.ac.th\/fac\/law\/professor\/%e0%b8%ad%e0%b8%b2%e0%b8%88%e0%b8%b2%e0%b8%a3%e0%b8%a2%e0%b9%8c%e0%b8%9e%e0%b8%b4%e0%b9%80%e0%b8%a8%e0%b8%a9\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1e\u0e34\u0e40\u0e28\u0e29<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-466ce5e\" data-id=\"466ce5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b63202d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b63202d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-bc60969\" data-id=\"bc60969\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a062d28 elementor-widget elementor-widget-awsm-team\" data-id=\"a062d28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"awsm-team.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"awsm-team-15969\" class=\"awsm-grid-wrapper\">\n\t\t\n\t\t\t<div class=\"awsm-grid list-style style-2 grid-2-col \">\n\t\t\t\t\t\t<div id=\"awsm-member-15969-15968\" class=\"awsm-grid-card awsm-team-item awsm-scale-anm awsm-all\">\n\t\t\t\t   <figure>\n\t\t\t\t\t <img fetchpriority=\"high\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.spu.ac.th\/fac\/law\/wp-content\/smush-webp\/sites\/8\/2025\/02\/\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c-\u0e14\u0e23.\u0e42\u0e2a\u0e20\u0e13-\u0e40\u0e08\u0e23\u0e34\u0e0d-667x1000.jpg.webp\" class=\"attachment-awsm_team size-awsm_team wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t <figcaption>\n\t\t\t\t\t\t\t<div class=\"awsm-personal-info\"><h3>\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e42\u0e2a\u0e20\u0e13 \u0e40\u0e08\u0e23\u0e34\u0e0d<\/h3><span>\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e15\u0e34\u0e23\u0e31\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/span><\/div>\n\t\t\t\t\t\t\t<div class=\"awsm-contact-info\">\n\t\t\t\t\t\t\t\t\n<p>\u0e1c\u0e28.\u0e14\u0e23. \u0e42\u0e2a\u0e20\u0e13 \u0e40\u0e08\u0e23\u0e34\u0e0d \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e41\u0e25\u0e30\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e07\u0e32\u0e19 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e04\u0e25\u0e31\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c, \u0e19\u0e31\u0e01\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e04\u0e21, \u0e1c\u0e39\u0e49\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e1b\u0e23\u0e30\u0e19\u0e2d\u0e21\u0e02\u0e49\u0e2d\u0e1e\u0e34\u0e1e\u0e32\u0e17\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e28\u0e32\u0e25\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07 \u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e40\u0e04\u0e22\u0e14\u0e33\u0e23\u0e07\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e19\u0e34\u0e15\u0e34\u0e01\u0e23\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1d\u0e48\u0e32\u0e22\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e0a.\u0e01\u0e32\u0e23\u0e0a\u0e48\u0e32\u0e07 \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19)<\/p>\n\n\n\n<p>\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<\/p>\n\n\n\n<p>\u2013 \u0e28\u0e28\u0e34\u0e23\u0e4c\u0e2d\u0e23 \u0e2d\u0e34\u0e19\u0e42\u0e15, \u0e16\u0e27\u0e31\u0e25\u0e22\u0e4c \u0e23\u0e38\u0e22\u0e32\u0e1e\u0e23, \u0e20\u0e32\u0e13\u0e38\u0e21\u0e32\u0e28 \u0e02\u0e31\u0e14\u0e40\u0e07\u0e32\u0e07\u0e32\u0e21, \u0e42\u0e2a\u0e20\u0e13 \u0e40\u0e08\u0e23\u0e34\u0e0d, \u0e41\u0e25\u0e30\u0e27\u0e19\u0e32\u0e20\u0e23\u0e13\u0e4c \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e24\u0e01\u0e29\u0e4c. (2566).&nbsp;\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e04\u0e14\u0e35\u0e17\u0e32\u0e07\u0e2d\u0e32\u0e0d\u0e32\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21. \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21 \u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1e\u0e23\u0e30\u0e1b\u0e23\u0e34\u0e22\u0e31\u0e15\u0e34\u0e18\u0e23\u0e23\u0e21\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e27\u0e31\u0e14\u0e2a\u0e23\u0e30\u0e40\u0e23\u0e35\u0e22\u0e07 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e28\u0e23\u0e35\u0e18\u0e23\u0e23\u0e21\u0e23\u0e32\u0e0a, 7 (10), (TCI 1)<\/p>\n\n\n\n<p>\u2013 \u0e40\u0e01\u0e23\u0e35\u0e22\u0e07\u0e44\u0e01\u0e23\u0e22\u0e28 \u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e44\u0e17\u0e22, \u0e1a\u0e38\u0e0d\u0e0a\u0e32\u0e25 \u0e17\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e22\u0e39\u0e23, \u0e40\u0e2a\u0e32\u0e27\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e40\u0e1e\u0e47\u0e0a\u0e23\u0e04\u0e25\u0e32\u0e22, \u0e1e\u0e23\u0e23\u0e13\u0e32 \u0e04\u0e13\u0e34\u0e15\u0e40\u0e19\u0e15\u0e23, \u0e41\u0e25\u0e30\u0e42\u0e2a\u0e20\u0e13 \u0e40\u0e08\u0e23\u0e34\u0e0d. (2566). \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2a\u0e39\u0e07\u0e2d\u0e32\u0e22\u0e38 4.0 \u0e43\u0e19\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e. \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 7 The 7th UTCC National Conference \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2b\u0e2d\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e44\u0e17\u0e22 \u0e04\u0e23\u0e1a\u0e23\u0e2d\u0e1a 60 \u0e1b\u0e35, \u0e43\u0e19\u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23\u0e17\u0e35\u0e48 6 \u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2566, \u0e2b\u0e19\u0e49\u0e32 652-666.<\/p>\n\n\n\n<p>\u2013 \u0e27\u0e31\u0e0a\u0e23\u0e1e\u0e07\u0e29\u0e4c \u0e15\u0e31\u0e19\u0e11\u0e4c\u0e1e\u0e23\u0e0a\u0e31\u0e22, \u0e42\u0e2a\u0e20\u0e13 \u0e40\u0e08\u0e23\u0e34\u0e0d, \u0e2d\u0e23\u0e38\u0e13\u0e35 \u0e19\u0e23\u0e34\u0e19\u0e17\u0e23\u0e01\u0e38\u0e25 \u0e13 \u0e2d\u0e22\u0e38\u0e18\u0e22\u0e32, \u0e01\u0e32\u0e0d\u0e08\u0e19\u0e32\u0e17 \u0e40\u0e23\u0e37\u0e2d\u0e07\u0e27\u0e23\u0e32\u0e01\u0e23, \u0e41\u0e25\u0e30\u0e27\u0e34\u0e44\u0e25\u0e27\u0e23\u0e23\u0e13 \u0e17\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e22\u0e39\u0e23. (2563). \u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e40\u0e0a\u0e34\u0e07\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49 Social Media Micro influencer \u0e43\u0e19\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e33\u0e2d\u0e32\u0e07\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e0a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e15\u0e23\u0e32\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e17\u0e35\u0e48\u0e08\u0e30\u0e0b\u0e37\u0e49\u0e2d \u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e40\u0e1f\u0e2a\u0e1a\u0e38\u0e4a\u0e04 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22. \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23 Tourism Disruption : The Way Forward &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 9, \u0e43\u0e19\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 18 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 2563 \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07, \u0e2b\u0e19\u0e49\u0e32 525-534<\/p>\n\n\n\n<p>\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<br>\u2013 \u0e20\u0e32\u0e19\u0e38\u0e21\u0e32\u0e28 \u0e02\u0e31\u0e14\u0e40\u0e07\u0e32\u0e07\u0e32\u0e21, \u0e28\u0e28\u0e34\u0e23\u0e4c\u0e2d\u0e23 \u0e2d\u0e34\u0e19\u0e42\u0e15, \u0e16\u0e27\u0e31\u0e25\u0e22\u0e4c \u0e23\u0e38\u0e22\u0e32\u0e1e\u0e23, \u0e41\u0e25\u0e30\u0e42\u0e2a\u0e20\u0e13 \u0e40\u0e08\u0e23\u0e34\u0e0d. (2566). \u0e01\u0e23\u0e13\u0e35\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e17\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e19\u0e23\u0e16\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e04\u0e49\u0e32\u0e07\u0e0a\u0e33\u0e23\u0e30\u0e04\u0e48\u0e32\u0e1b\u0e23\u0e31\u0e1a \u0e15\u0e32\u0e21 \u0e1e.\u0e23.\u0e1a. \u0e08\u0e23\u0e32\u0e08\u0e23\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e1e.\u0e28. 2522 \u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e01\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e30\u0e07\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e2b\u0e25\u0e31\u0e01\u0e10\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e35\u0e1a\u0e20\u0e32\u0e29\u0e35 (\u0e1b\u0e49\u0e32\u0e22\u0e27\u0e07\u0e01\u0e25\u0e21) \u0e09\u0e1a\u0e31\u0e1a\u0e08\u0e23\u0e34\u0e07 \u0e44\u0e14\u0e48\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 ? (\u0e1c\u0e25\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e19\u0e31\u0e22 \u0e1e.\u0e28. 2565 \u0e15\u0e48\u0e2d\u0e21\u0e32\u0e15\u0e23\u0e32 140 \u0e41\u0e25\u0e30 141 \u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e08\u0e23\u0e32\u0e08\u0e23\u0e17\u0e32\u0e07\u0e1a\u0e01 \u0e1e.\u0e28. 2522). \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04 (\u0e2a\u0e32\u0e02\u0e32\u0e21\u0e19\u0e38\u0e29\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c), 10 (3), (TCI 2<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 :<\/strong><\/h4>\n\n\n\n<p>\u2013 \u0e1b\u0e23.\u0e14. \u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07<br>\u2013 \u0e19.\u0e21. \u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e21\u0e2b\u0e32\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e08\u0e38\u0e2c\u0e32\u0e25\u0e07\u0e01\u0e23\u0e13\u0e4c\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22<br>\u2013 \u0e19.\u0e1a. \u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e21\u0e04\u0e33\u0e41\u0e2b\u0e07<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t <\/figcaption>\n\t\t\t\t   <\/figure>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"awsm-member-15969-15973\" class=\"awsm-grid-card awsm-team-item awsm-scale-anm awsm-all\">\n\t\t\t\t   <figure>\n\t\t\t\t\t <img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.spu.ac.th\/fac\/law\/wp-content\/smush-webp\/sites\/8\/2025\/02\/\u0e2d.\u0e40\u0e14\u0e35\u0e22\u0e23\u0e4c-667x1000.jpg.webp\" class=\"attachment-awsm_team size-awsm_team wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t <figcaption>\n\t\t\t\t\t\t\t<div class=\"awsm-personal-info\"><h3>\u0e14\u0e23.\u0e28\u0e34\u0e27\u0e1e\u0e23 \u0e40\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e18\u0e4c<\/h3><span>\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e15\u0e34\u0e23\u0e31\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/span><\/div>\n\t\t\t\t\t\t\t<div class=\"awsm-contact-info\">\n\t\t\t\t\t\t\t\t\n<p>\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<br>\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22<br>\u2013 \u0e18\u0e31\u0e0d\u0e0d\u0e32\u0e20\u0e31\u0e2a \u0e17\u0e2d\u0e07\u0e21\u0e38\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c \u0e41\u0e25\u0e30\u0e28\u0e34\u0e27\u0e1e\u0e23 \u0e40\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e18\u0e4c. (2565). \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e15\u0e25\u0e32\u0e14\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e32\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 (THE DEVELOPMENT OF THE INTELLECTUAL PROPERTY TRADING MARKET AS COLLATERAL UNDER THE BUSINESS SECURITY LAW). \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e17\u0e31\u0e01\u0e29\u0e34\u0e13, 10 (12), \u0e2b\u0e19\u0e49\u0e32 206-220.<br>\u2013 \u0e1b\u0e20\u0e34\u0e13\u0e27\u0e34\u0e0a \u0e23\u0e2d\u0e14\u0e1a\u0e32\u0e07\u0e22\u0e32\u0e07, \u0e28\u0e34\u0e27\u0e1e\u0e23 \u0e40\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e39\u0e0a\u0e35\u0e27\u0e23\u0e23\u0e13 \u0e15\u0e21\u0e34\u0e28\u0e32\u0e19\u0e19\u0e17\u0e4c. (2565). \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e32\u0e1a\u0e1b\u0e23\u0e32\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e19\u0e40\u0e02\u0e15\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e15\u0e33\u0e23\u0e27\u0e08\u0e20\u0e39\u0e18\u0e23\u0e20\u0e32\u0e04 2. \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e21\u0e19\u0e38\u0e29\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21, \u0e1b\u0e35\u0e17\u0e35\u0e48 41 \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 2 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21-\u0e40\u0e21\u0e29\u0e32\u0e22\u0e19 2565, \u0e2b\u0e19\u0e49\u0e32 48-58.<br>\u2013 \u0e28\u0e34\u0e27\u0e1e\u0e23 \u0e40\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e18\u0e4c. (2563). \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08: \u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e23\u0e13\u0e35\u0e1e\u0e31\u0e19\u0e18\u0e38\u0e4c\u0e1e\u0e37\u0e0a (PROBLEMS ON THE ENFORCEMENT OF BUSINESS SECURITY LAW: CASE STUDY OF PLANT VARIETIES). \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21, 4 (4), \u0e2b\u0e19\u0e49\u0e32 79-87.<br>\u2013 \u0e28\u0e34\u0e27\u0e1e\u0e23 \u0e40\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e18\u0e4c. (2562). \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e2a\u0e23\u0e23\u0e04\u0e01\u0e32\u0e23\u0e1a\u0e31\u0e07\u0e04\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e1a\u0e31\u0e0d\u0e0d\u0e31\u0e15\u0e34\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08 \u0e1e.\u0e28. 2558: \u0e28\u0e36\u0e01\u0e29\u0e32\u0e01\u0e23\u0e13\u0e35\u0e04\u0e27\u0e32\u0e21\u0e25\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 (ENFORCEMENT OF THE BUSINESS SECURITY ACT BE 2558 ON TRADE SECRETS AS COLLATERAL). \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21, 13 (2), \u0e2b\u0e19\u0e49\u0e32 85-92.<br>\u2013 \u0e18\u0e27\u0e31\u0e0a\u0e0a\u0e31\u0e22 \u0e07\u0e32\u0e21\u0e40\u0e25\u0e34\u0e28, \u0e23\u0e38\u0e48\u0e07\u0e41\u0e2a\u0e07 \u0e01\u0e24\u0e15\u0e22\u0e1e\u0e07\u0e29\u0e4c, \u0e02\u0e19\u0e34\u0e29\u0e10\u0e32 \u0e2a\u0e38\u0e02\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e4c \u0e41\u0e25\u0e30 \u0e28\u0e34\u0e27\u0e1e\u0e23 \u0e40\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e18\u0e4c. (2563). \u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e32\u0e21\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e27\u0e34\u0e0a\u0e32\u0e0a\u0e35\u0e1e\u0e2a\u0e37\u0e48\u0e2d\u0e21\u0e27\u0e25\u0e0a\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e25\u0e30\u0e40\u0e21\u0e34\u0e14\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25. \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e1b\u0e0b\u0e34\u0e1f\u0e34\u0e04, \u0e1b\u0e35\u0e17\u0e35\u0e48 6 \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 3 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19-\u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563, \u0e2b\u0e19\u0e49\u0e32 381-387.<br>\u2013 \u0e17\u0e34\u0e1e\u0e22\u0e4c\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e01\u0e38\u0e2b\u0e25\u0e32\u0e1a\u0e41\u0e01\u0e49\u0e27, \u0e28\u0e34\u0e27\u0e1e\u0e23 \u0e40\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e18\u0e4c, \u0e41\u0e25\u0e30 \u0e04\u0e21\u0e2a\u0e31\u0e19 \u0e2a\u0e38\u0e02\u0e21\u0e32\u0e01. (2563). \u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e15\u0e31\u0e27\u0e0a\u0e31\u0e48\u0e27\u0e04\u0e23\u0e32\u0e27\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e25\u0e31\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e43\u0e19\u0e0a\u0e31\u0e49\u0e19\u0e2a\u0e2d\u0e1a\u0e2a\u0e27\u0e19. \u0e27\u0e32\u0e23\u0e2a\u0e32\u0e23\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21, \u0e1b\u0e35\u0e17\u0e35\u0e48 15, \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 2 (\u0e21.\u0e04.-\u0e21\u0e34.\u0e22. 2563), \u0e2b\u0e19\u0e49\u0e32 98-107.<\/p>\n\n\n\n<p>\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<br>\u2013 Saowakon, S., Sudtachai, W., Jaroennonthasit, P. and Kanavittaya W. (2022). Laws Guaranteeing The Purchase Agreement Of Pet Dogs And Cats. Proceedings of the 17th International Sripatum University Conference (SPUCON2022). p.166-173.<br>\u2013 Traisiriwanich, P., Saowakon, S., Yeesarapat, B. and Jaroennonthasit, P. (2022). Legal Issues Regarding The Rights Of Community Participation In Sustainably Managing Natural Resources And Environment In Thailand. Proceedings of the 17th International Sripatum University Conference (SPUCON2022). p.159-165.<br>\u2013 \u0e28\u0e34\u0e27\u0e1e\u0e23 \u0e40\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e1a\u0e38\u0e0d\u0e0a\u0e19\u0e30 \u0e22\u0e35\u0e48\u0e2a\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e4c. (2564). \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e25\u0e47\u0e2d\u0e1a\u0e1a\u0e35\u0e49\u0e22\u0e35\u0e2a\u0e15\u0e4c. \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34 \u201c\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 16\u201d, \u0e2b\u0e19\u0e49\u0e32 987-994.<br>\u0e1a\u0e38\u0e0d\u0e0a\u0e19\u0e30 \u0e22\u0e35\u0e48\u0e2a\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e28\u0e34\u0e27\u0e1e\u0e23 \u0e40\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e18\u0e4c. (2564). \u0e01\u0e32\u0e23\u0e23\u0e30\u0e07\u0e31\u0e1a\u0e02\u0e49\u0e2d\u0e1e\u0e34\u0e1e\u0e32\u0e17\u0e42\u0e14\u0e22\u0e43\u0e0a\u0e49\u0e01\u0e0e\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19. \u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e2a\u0e37\u0e1a\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34 \u201c\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e2a\u0e38\u0e23\u0e32\u0e29\u0e0e\u0e23\u0e4c\u0e18\u0e32\u0e19\u0e35\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 16\u201d, \u0e2b\u0e19\u0e49\u0e32 987-994.<br>\u2013 \u0e28\u0e34\u0e27\u0e1e\u0e23 \u0e40\u0e2a\u0e32\u0e27\u0e04\u0e19\u0e18\u0e4c \u0e41\u0e25\u0e30\u0e0a\u0e37\u0e48\u0e19\u0e2a\u0e38\u0e21\u0e19 \u0e13 \u0e19\u0e04\u0e23, \u201c\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e41\u0e25\u0e30\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32 (THE PROMOTION AND PROTECTION OF THE EXHIBITION BUSINESS)\u201d \u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e0a\u0e32\u0e15\u0e34\u0e41\u0e25\u0e30\u0e19\u0e32\u0e19\u0e32\u0e0a\u0e32\u0e15\u0e34 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 15 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2563 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19 \u0e43\u0e19\u0e27\u0e31\u0e19\u0e28\u0e38\u0e01\u0e23\u0e4c\u0e17\u0e35\u0e48 18 \u0e18\u0e31\u0e19\u0e27\u0e32\u0e04\u0e21 2563, \u0e2b\u0e19\u0e49\u0e32 387-396.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 :<\/strong><\/h4>\n\n\n\n<p>\u2013 \u0e19.\u0e14. \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21<br>\u2013 \u0e19.\u0e21. (\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21<br>\u2013 \u0e19.\u0e1a. (\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d<\/p>\n\n\n\n<p>\u0e42\u0e17\u0e23 : 02 579 1111 \u0e15\u0e48\u0e2d 2388<\/p>\n\n\n\n<p>\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e4c : siwaporn.so@spu.ac.th<\/p>\n\n\n\n<p><\/p>\n<div class=\"awsm-contact-details\"><p><span>Email:<\/span><a href=\"mailto:siwaporn.so@spu.ac.th\">siwaporn.so@spu.ac.th<\/a><\/p><\/div>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t <\/figcaption>\n\t\t\t\t   <\/figure>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"awsm-member-15969-15984\" class=\"awsm-grid-card awsm-team-item awsm-scale-anm awsm-all\">\n\t\t\t\t   <figure>\n\t\t\t\t\t <img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.spu.ac.th\/fac\/law\/wp-content\/smush-webp\/sites\/8\/2025\/02\/\u0e14\u0e23.\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e1e\u0e07\u0e29\u0e4c-\u0e01\u0e38\u0e21\u0e32\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c-667x1000.jpg.webp\" class=\"attachment-awsm_team size-awsm_team wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t <figcaption>\n\t\t\t\t\t\t\t<div class=\"awsm-personal-info\"><h3>\u0e14\u0e23.\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e1e\u0e07\u0e29\u0e4c \u0e01\u0e38\u0e21\u0e32\u0e23\u0e2a\u0e34\u0e07\u0e2b\u0e4c<\/h3><span>\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e15\u0e34\u0e23\u0e31\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/span><\/div>\n\t\t\t\t\t\t\t<div class=\"awsm-contact-info\">\n\t\t\t\t\t\t\t\t\n<p>\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<br>\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e27\u0e34\u0e08\u0e31\u0e22<br>\u2013 Kumansing, S. (2021). Public Defender for the Rights to Access to Justice Civil Cases. Journal of Social Science for Local Rajabhat Mahasarakham University. 5 (1), p.p. 220-226.<\/p>\n\n\n\n<p>\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e17\u0e32\u0e07\u0e27\u0e34\u0e0a\u0e32\u0e01\u0e32\u0e23<br>\u2013 Kumansing, S. and Thueaksaeng, L. (2020). The role of lawyers and the postmortem examination. (GRADSPUCON 2020) The 15th Regional Conference on Graduate Research 2020 Theme Sustainable Business Growth, Challenges, Measures and Solutions in Global Scenario. 18 January 2020, Sripatum University, Khon Kaen Campus, Khon Kaen,Thailand. p.p. 107-108.<br>\u2013 Kumansing, S. and Sangkananta, K. (2020). The role of lawyers and natural resources and the environment. (GRADSPUCON 2020) The 15th Regional Conference on Graduate Research 2020 Theme Sustainable BusinessGrowth, Challenges, Measures and Solutions in Global Scenario. 18 January 2020, Sripatum University, Khon Kaen Campus, KhonKaen,Thailand. p.p. 112-113<br>\u2013 Kumansing, S. and Aonrat, P. (2020). Professional compulsory liability insurance Medical. (GRADSPUCON 2020) The 15th Regional Conference on Graduate Research 2020 Theme Sustainable Business Growth, Challenges, Measures and Solutions in Global Scenario. 18 January 2020, Sripatum University, Khon Kaen Campus, Khon Kaen,Thailand. p.p. 108-109.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 :<\/strong><\/h4>\n\n\n\n<p>\u0e19.\u0e14. \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21<br>\u0e19.\u0e21. \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21<br>\u0e19.\u0e1a. (\u0e19\u0e34\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t <\/figcaption>\n\t\t\t\t   <\/figure>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"awsm-member-15969-15988\" class=\"awsm-grid-card awsm-team-item awsm-scale-anm awsm-all\">\n\t\t\t\t   <figure>\n\t\t\t\t\t <img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.spu.ac.th\/fac\/law\/wp-content\/smush-webp\/sites\/8\/2025\/02\/\u0e14\u0e23.\u0e1b\u0e20\u0e1e\u0e1e\u0e25-\u0e40\u0e15\u0e34\u0e21\u0e18\u0e35\u0e23\u0e01\u0e34\u0e08-667x1000.jpg.webp\" class=\"attachment-awsm_team size-awsm_team wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t <figcaption>\n\t\t\t\t\t\t\t<div class=\"awsm-personal-info\"><h3>\u0e14\u0e23.\u0e1b\u0e20\u0e1e\u0e1e\u0e25 \u0e40\u0e15\u0e34\u0e21\u0e18\u0e35\u0e23\u0e01\u0e34\u0e08<\/h3><span>\u0e2d\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e15\u0e34\u0e23\u0e31\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/span><\/div>\n\t\t\t\t\t\t\t<div class=\"awsm-contact-info\">\n\t\t\t\t\t\t\t\t\n<h4 class=\"wp-block-heading\"><strong>\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 :<\/strong><\/h4>\n\n\n\n<p>\u0e1b\u0e23.\u0e14. (\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e28\u0e32\u0e2a\u0e19\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c), 2555<br>\u0e23\u0e1b.\u0e21. 2546<br>\u0e1a\u0e18.\u0e1a. 2542<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t <\/figcaption>\n\t\t\t\t   <\/figure>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"awsm-member-15969-15992\" class=\"awsm-grid-card awsm-team-item awsm-scale-anm awsm-all\">\n\t\t\t\t   <figure>\n\t\t\t\t\t <img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.spu.ac.th\/fac\/law\/wp-content\/smush-webp\/sites\/8\/2025\/02\/\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e01\u0e21\u0e25\u0e0a\u0e19\u0e01-\u0e2a\u0e37\u0e1a\u0e40\u0e2a\u0e32\u0e30-667x1000.jpg.webp\" class=\"attachment-awsm_team size-awsm_team wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t <figcaption>\n\t\t\t\t\t\t\t<div class=\"awsm-personal-info\"><h3>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e01\u0e21\u0e25\u0e0a\u0e19\u0e01 \u0e2a\u0e37\u0e1a\u0e40\u0e2a\u0e32\u0e30<\/h3><span>\u0e40\u0e25\u0e02\u0e32\u0e19\u0e38\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e15\u0e34\u0e23\u0e31\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/span><\/div>\n\t\t\t\t\t\t\t<div class=\"awsm-contact-info\">\n\t\t\t\t\t\t\t\t\n<h4 class=\"wp-block-heading\"><strong>\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 :<\/strong><\/h4>\n\n\n\n<p>\u0e23\u0e1b.\u0e21. (\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e28\u0e32\u0e2a\u0e19\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e21\u0e2b\u0e32\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e31\u0e15\u0e19\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15<br>\u0e1a.\u0e18 (\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e41\u0e23\u0e21\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e31\u0e15\u0e19\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15<\/p>\n\n\n\n<p>\u0e42\u0e17\u0e23 : 02-579-1111 \u0e15\u0e48\u0e2d 2388<\/p>\n\n\n\n<p>\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e4c : kamolchanok.su@spu.ac.th<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t <\/figcaption>\n\t\t\t\t   <\/figure>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"awsm-member-15969-15996\" class=\"awsm-grid-card awsm-team-item awsm-scale-anm awsm-all\">\n\t\t\t\t   <figure>\n\t\t\t\t\t <img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.spu.ac.th\/fac\/law\/wp-content\/smush-webp\/sites\/8\/2025\/02\/\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2a\u0e38\u0e0a\u0e32\u0e27\u0e14\u0e35-\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e40\u0e01\u0e29\u0e21-1-667x1000.jpg.webp\" class=\"attachment-awsm_team size-awsm_team wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t <figcaption>\n\t\t\t\t\t\t\t<div class=\"awsm-personal-info\"><h3>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e2a\u0e38\u0e0a\u0e32\u0e27\u0e14\u0e35 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e40\u0e01\u0e29\u0e21<\/h3><span>\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e23\u0e31\u0e0a\u0e0d\u0e32\u0e14\u0e38\u0e29\u0e0e\u0e35\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15 \u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e34\u0e15\u0e34\u0e23\u0e31\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/span><\/div>\n\t\t\t\t\t\t\t<div class=\"awsm-contact-info\">\n\t\t\t\t\t\t\t\t\n<h4 class=\"wp-block-heading\"><strong>\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 :<\/strong><\/h4>\n\n\n\n<p>\u0e04.\u0e1a. (\u0e01\u0e32\u0e23\u0e27\u0e31\u0e14\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32) \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e40\u0e17\u0e1e\u0e2a\u0e15\u0e23\u0e35<\/p>\n\n\n\n<p>\u0e42\u0e17\u0e23 : 02-579-1111 \u0e15\u0e48\u0e2d 2388<\/p>\n\n\n\n<p>\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e4c : suchawadee.ju@spu.ac.th<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t <\/figcaption>\n\t\t\t\t   <\/figure>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-494f961 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"494f961\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ec80a0f\" data-id=\"ec80a0f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fdc215 elementor-widget elementor-widget-heading\" data-id=\"0fdc215\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Are You Ready To Start?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7f67453\" data-id=\"7f67453\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de980f5 elementor-align-right elementor-tablet-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"de980f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-size-sm elementor-animation-float\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e14\u0e23.\u0e42\u0e2a\u0e20\u0e13 \u0e40\u0e08\u0e23\u0e34\u0e0d \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e1b\u0e23\u0e31 [&hellip;]<\/p>\n","protected":false},"author":40,"featured_media":0,"parent":176,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-300","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.spu.ac.th\/fac\/law\/wp-json\/wp\/v2\/pages\/300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spu.ac.th\/fac\/law\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.spu.ac.th\/fac\/law\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/law\/wp-json\/wp\/v2\/users\/40"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/law\/wp-json\/wp\/v2\/comments?post=300"}],"version-history":[{"count":0,"href":"https:\/\/www.spu.ac.th\/fac\/law\/wp-json\/wp\/v2\/pages\/300\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/law\/wp-json\/wp\/v2\/pages\/176"}],"wp:attachment":[{"href":"https:\/\/www.spu.ac.th\/fac\/law\/wp-json\/wp\/v2\/media?parent=300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}