{"id":1825,"date":"2023-04-10T04:36:14","date_gmt":"2023-04-10T04:36:14","guid":{"rendered":"https:\/\/www.spu.ac.th\/informatics\/?page_id=1825"},"modified":"2023-07-13T08:06:40","modified_gmt":"2023-07-13T08:06:40","slug":"staff-6","status":"publish","type":"page","link":"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-6\/","title":{"rendered":"\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e04\u0e13\u0e30"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1825\" class=\"elementor elementor-1825\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f28d34 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"6f28d34\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-49b991c\" data-id=\"49b991c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0c10525 elementor-widget elementor-widget-template\" data-id=\"0c10525\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"94\" class=\"elementor elementor-94\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d056a5b elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"6d056a5b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:&quot;1959&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.spu.ac.th\\\/informatics\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2023\\\/02\\\/20170316104006xfAEsP1.jpg&quot;},{&quot;id&quot;:&quot;1960&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.spu.ac.th\\\/informatics\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2023\\\/02\\\/20221001113449UG7zS7a.png&quot;},{&quot;id&quot;:&quot;1961&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.spu.ac.th\\\/informatics\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2023\\\/02\\\/20230214140133pHZtyev.jpg&quot;},{&quot;id&quot;:&quot;1962&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.spu.ac.th\\\/informatics\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2023\\\/02\\\/202203231400564I1FqLA.jpg&quot;}],&quot;jet_parallax_layout_list&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ec76f0c elementor-hidden-desktop elementor-hidden-tablet\" data-id=\"3ec76f0c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:&quot;1854&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.spu.ac.th\\\/fac\\\/informatics\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2023\\\/04\\\/20221001113500nyHy9cv.png&quot;},{&quot;id&quot;:&quot;1852&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.spu.ac.th\\\/fac\\\/informatics\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2023\\\/04\\\/20170316103957WNPDr5v.jpg&quot;},{&quot;id&quot;:&quot;1853&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.spu.ac.th\\\/fac\\\/informatics\\\/wp-content\\\/uploads\\\/sites\\\/10\\\/2023\\\/04\\\/20220323141729VckBsEO.jpg&quot;}],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a1906e4 elementor-section-height-min-height elementor-section-items-stretch elementor-section-boxed elementor-section-height-default\" data-id=\"2a1906e4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-73c7c6c5\" data-id=\"73c7c6c5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-445fdc76 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"445fdc76\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-2fd12cac\" data-id=\"2fd12cac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b5cdb0b elementor-widget elementor-widget-heading\" data-id=\"5b5cdb0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">5<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43620604 elementor-widget elementor-widget-heading\" data-id=\"43620604\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-16ea2d39\" data-id=\"16ea2d39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7093438d elementor-widget elementor-widget-heading\" data-id=\"7093438d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f451e68 elementor-widget elementor-widget-heading\" data-id=\"1f451e68\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">AIot (ai+iot)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-efaa85a\" data-id=\"efaa85a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24742ad7 elementor-widget elementor-widget-heading\" data-id=\"24742ad7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e07\u0e32\u0e19<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e7e9d14 elementor-widget elementor-widget-heading\" data-id=\"3e7e9d14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-78ed43f2\" data-id=\"78ed43f2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-681f5bbf elementor-widget elementor-widget-heading\" data-id=\"681f5bbf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-627da75 elementor-widget elementor-widget-heading\" data-id=\"627da75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-64942808\" data-id=\"64942808\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25aae35d elementor-widget elementor-widget-heading\" data-id=\"25aae35d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e15\u0e34\u0e14 1 \u0e43\u0e19\u0e04\u0e13\u0e30<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb8cce3 elementor-widget elementor-widget-heading\" data-id=\"3bb8cce3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0e17\u0e35\u0e48\u0e21\u0e35\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2a\u0e39\u0e07<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e51193e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e51193e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78b6191\" data-id=\"78b6191\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d67267e elementor-widget elementor-widget-template\" data-id=\"d67267e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:150,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"1993\" class=\"elementor elementor-1993\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f90a18 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f90a18\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-40ea7f3\" data-id=\"40ea7f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3bfa34b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3bfa34b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-debe998\" data-id=\"debe998\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b1ebdf elementor-widget elementor-widget-heading\" data-id=\"1b1ebdf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e04\u0e13\u0e30\/\u0e2a\u0e32\u0e02\u0e32<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6319f34\" data-id=\"6319f34\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96f331d elementor-icon-list--layout-inline elementor-align-end elementor-tablet-align-start elementor-mobile-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"96f331d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/spu.informatics\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-facebook-f\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/twitter.com\/spufriends\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-twitter\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/user\/spuit2012\" target=\"_blank\" rel=\"noopener\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fab fa-youtube\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4e3c3b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4e3c3b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-24e91c7\" data-id=\"24e91c7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44cc657 elementor-nav-menu__align-start elementor-nav-menu--dropdown-none elementor-widget elementor-widget-nav-menu\" data-id=\"44cc657\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;}}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-44cc657\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-386\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/\" class=\"elementor-item\">\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-382\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-1\/\" class=\"elementor-item\">\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-385\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-2\/\" class=\"elementor-item\">\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-384\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-3\/\" class=\"elementor-item\">\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-383\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-4\/\" class=\"elementor-item\">\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1833\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-5\/\" class=\"elementor-item\">\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1832\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-6\/\" class=\"elementor-item\">\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e04\u0e13\u0e30<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-44cc657\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-386\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-382\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-1\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-385\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-2\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1a\u0e31\u0e13\u0e11\u0e34\u0e15\u0e28\u0e36\u0e01\u0e29\u0e32<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-384\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-3\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-383\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-4\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e28\u0e27\u0e01\u0e23\u0e23\u0e21\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1833\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-5\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2a\u0e32\u0e02\u0e32\u0e27\u0e34\u0e0a\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e32\u0e23\u0e04\u0e2d\u0e21\u0e1e\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e0b\u0e2d\u0e1f\u0e15\u0e4c\u0e41\u0e27\u0e23\u0e4c<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1832\"><a href=\"https:\/\/www.spu.ac.th\/fac\/informatics\/professor\/staff-6\/\" class=\"elementor-item\" tabindex=\"-1\">\u0e2a\u0e48\u0e27\u0e19\u0e07\u0e32\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e04\u0e13\u0e30<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9d5ae1b\" data-id=\"9d5ae1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a6791a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6791a4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b9511b0\" data-id=\"b9511b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f920bd7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f920bd7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e562bd8\" data-id=\"e562bd8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d22d059 elementor-widget elementor-widget-shortcode\" data-id=\"d22d059\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><div id=\"awsm-team-2946\" class=\"awsm-grid-wrapper\">\n\t\t\n\t<div class=\"awsm-modal\">\n\t\t\t<div class=\"awsm-grid-modal awsm-grid modal-style style-1 grid-3-col \">\n\t\t\t\t\t\t<div id=\"awsm-member-2946-2928\" class=\"awsm-grid-card awsm-team-item awsm-scale-anm awsm-all\">\n\t\t\t\t\t<span id=\"tigger-style-2946-2928\" class=\"awsm-team-link-control awsm-modal-trigger awsm-modal-trigger-2928\" data-trigger=\"#modal-style-2946-2928\">\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-content\/uploads\/sites\/10\/2023\/07\/\u0e2d\u0e31\u0e0d\u0e0a\u0e25\u0e35-1-667x1000.jpg\" class=\"attachment-awsm_team size-awsm_team wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t<div class=\"awsm-personal-info\"><span>\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/span><h3>\u0e04\u0e38\u0e13\u0e2d\u0e31\u0e0d\u0e0a\u0e25\u0e35 \u0e1a\u0e31\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32<\/h3><\/div>\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"awsm-member-2946-2930\" class=\"awsm-grid-card awsm-team-item awsm-scale-anm awsm-all\">\n\t\t\t\t\t<span id=\"tigger-style-2946-2930\" class=\"awsm-team-link-control awsm-modal-trigger awsm-modal-trigger-2930\" data-trigger=\"#modal-style-2946-2930\">\n\t\t\t\t\t\t<figure>\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-content\/uploads\/sites\/10\/2023\/07\/\u0e01\u0e31\u0e0d\u0e0d\u0e32\u0e20\u0e31\u0e04-1-667x1000.jpg\" class=\"attachment-awsm_team size-awsm_team wp-post-image\" alt=\"\" \/>\t\t\t\t\t\t\t<figcaption>\n\t\t\t\t\t\t\t\t<div class=\"awsm-personal-info\"><span>\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e17\u0e35\u0e48<\/span><h3>\u0e04\u0e38\u0e13\u0e01\u0e31\u0e0d\u0e0d\u0e32\u0e20\u0e31\u0e04 \u0e1a\u0e38\u0e0d\u0e0a\u0e34\u0e15<\/h3><\/div>\t\t\t\t\t\t\t<\/figcaption>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<div class=\"awsm-modal-items modal-style style-1 grid-3-col \">\n\t\t\t<span class=\"awsm-team-link-control awsm-modal-close\"><\/span>\n\t\t\t<div class=\"awsm-modal-items-main\">\n\t\t\t\t<span class=\"awsm-team-link-control awsm-nav-item awsm-nav-left\"><\/span>\n\t\t\t\t\t<div id=\"modal-style-2946-2928\" class=\"awsm-modal-item awsm-scale-anm awsm-modal-hidden awsm-all \" data-info=\"2928\">\n\t<div id=\"awsm-member-info-2946-2928\" class=\"awsm-modal-content\">\n\t\t<div class=\"awsm-modal-content-main\">\n\t\t\t<div class=\"awsm-image-main\">\n\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-content\/uploads\/sites\/10\/2023\/07\/\u0e2d\u0e31\u0e0d\u0e0a\u0e25\u0e35-1-667x1000.jpg\" class=\"attachment-awsm_team size-awsm_team wp-post-image\" alt=\"\" \/>\t\t\t<\/div>\n\t\t\t<div class=\"awsm-modal-details\">\n\t\t\t\t<div class=\"awsm-modal-content-inner\">\n\t\t\t\t\t<h3>\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/h3><h2>\u0e04\u0e38\u0e13\u0e2d\u0e31\u0e0d\u0e0a\u0e25\u0e35 \u0e1a\u0e31\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32<\/h2><h4><b>\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 :<\/b><\/h4>\n<div class=\"edu-detail\">\n<p>\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35: (\u0e2a.\u0e1a.\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c)<br \/>\n\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e21\u0e2b\u0e32\u0e2a\u0e32\u0e23\u0e04\u0e32\u0e21<\/p>\n<p>\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e42\u0e17: (\u0e27\u0e17.\u0e21.\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28)<br \/>\n\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21<\/p>\n<\/div>\n<div class=\"awsm-contact-details\"><p><span>Tel:<\/span>02 579 1111 \u0e15\u0e48\u0e2d 2196<\/p><p><span>Email:<\/span><a href=\"mailto:unchalee.bu@spu.ac.th\">unchalee.bu@spu.ac.th<\/a><\/p><\/div>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<div id=\"modal-style-2946-2930\" class=\"awsm-modal-item awsm-scale-anm awsm-modal-hidden awsm-all \" data-info=\"2930\">\n\t<div id=\"awsm-member-info-2946-2930\" class=\"awsm-modal-content\">\n\t\t<div class=\"awsm-modal-content-main\">\n\t\t\t<div class=\"awsm-image-main\">\n\t\t\t\t<img decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-content\/uploads\/sites\/10\/2023\/07\/\u0e01\u0e31\u0e0d\u0e0d\u0e32\u0e20\u0e31\u0e04-1-667x1000.jpg\" class=\"attachment-awsm_team size-awsm_team wp-post-image\" alt=\"\" \/>\t\t\t<\/div>\n\t\t\t<div class=\"awsm-modal-details\">\n\t\t\t\t<div class=\"awsm-modal-content-inner\">\n\t\t\t\t\t<h3>\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e32\u0e17\u0e35\u0e48<\/h3><h2>\u0e04\u0e38\u0e13\u0e01\u0e31\u0e0d\u0e0d\u0e32\u0e20\u0e31\u0e04 \u0e1a\u0e38\u0e0d\u0e0a\u0e34\u0e15<\/h2><h4><b>\u0e27\u0e38\u0e12\u0e34\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 :<\/b><\/h4>\n<div class=\"edu-detail\">\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 : \u0e04\u0e13\u0e30\u0e19\u0e34\u0e40\u0e17\u0e28\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<br \/>\n\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21<\/div>\n<div class=\"awsm-contact-details\"><p><span>Tel:<\/span>02 579 1111 \u0e15\u0e48\u0e2d 2196<\/p><p><span>Email:<\/span><a href=\"mailto:Kanyapak.bo@spu.ac.th\">Kanyapak.bo@spu.ac.th<\/a><\/p><\/div>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t<span class=\"awsm-team-link-control awsm-nav-item awsm-nav-right\"><\/span>\n\t\t\t   <\/div>\n\t\t<\/div>\n\t\t<\/div>\n<\/div>\n\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-62e460d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62e460d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b1395f0\" data-id=\"b1395f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e01d5c6 elementor-widget elementor-widget-heading\" data-id=\"e01d5c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Are You Ready To Start?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5832661\" data-id=\"5832661\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0e5b01 elementor-align-right elementor-tablet-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"b0e5b01\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.spu.ac.th\/register.landing.php\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-long-arrow-alt-right\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Are You Ready To Start? \u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19<\/p>\n","protected":false},"author":43,"featured_media":0,"parent":176,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1825","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-json\/wp\/v2\/pages\/1825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-json\/wp\/v2\/comments?post=1825"}],"version-history":[{"count":0,"href":"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-json\/wp\/v2\/pages\/1825\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-json\/wp\/v2\/pages\/176"}],"wp:attachment":[{"href":"https:\/\/www.spu.ac.th\/fac\/informatics\/wp-json\/wp\/v2\/media?parent=1825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}