{"id":2772,"date":"2025-03-31T06:26:31","date_gmt":"2025-03-31T06:26:31","guid":{"rendered":"https:\/\/www.spu.ac.th\/department\/tlc\/?p=2772"},"modified":"2025-03-31T08:24:57","modified_gmt":"2025-03-31T08:24:57","slug":"spu-micro-credentials","status":"publish","type":"post","link":"https:\/\/www.spu.ac.th\/department\/tlc\/2025\/03\/31\/spu-micro-credentials\/","title":{"rendered":"\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 Kick Off \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 SPU-Micro Credentials \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15"},"content":{"rendered":"<p>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 Kick Off \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 SPU-Micro Credentials \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15<\/p>\n<p>31 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2568 \u2013 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Kick Off \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 SPU-Micro Credentials \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a ZOOM \u0e42\u0e14\u0e22\u0e21\u0e35\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01 15 \u0e04\u0e13\u0e30\/\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e41\u0e1c\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e17\u0e35\u0e21\u0e42\u0e04\u0e49\u0e0a \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35 (KMUTT)<\/p>\n<p>\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 Micro Credentials \u0e2b\u0e23\u0e37\u0e2d \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e2d\u0e14\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e1a\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15<\/p>\n<p>\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e21\u0e35\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 6 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e08\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e32\u0e02\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07<\/p>\n<p>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e39\u0e48\u0e2d\u0e19\u0e32\u0e04\u0e15!<\/p>\n<p>#SPUMicroCredentials #MicroCredentials #LifelongLearning #EducationInnovation #SPU<\/p>\n<p style=\"text-align: center\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-2775\" src=\"https:\/\/www.spu.ac.th\/department\/tlc\/wp-content\/uploads\/sites\/19\/2025\/03\/15MC.jpg\" alt=\"\" width=\"1080\" height=\"1080\" srcset=\"https:\/\/www.spu.ac.th\/department\/tlc\/wp-content\/uploads\/sites\/19\/2025\/03\/15MC.jpg 1080w, https:\/\/www.spu.ac.th\/department\/tlc\/wp-content\/uploads\/sites\/19\/2025\/03\/15MC-300x300.jpg 300w, https:\/\/www.spu.ac.th\/department\/tlc\/wp-content\/uploads\/sites\/19\/2025\/03\/15MC-1024x1024.jpg 1024w, https:\/\/www.spu.ac.th\/department\/tlc\/wp-content\/uploads\/sites\/19\/2025\/03\/15MC-150x150.jpg 150w, https:\/\/www.spu.ac.th\/department\/tlc\/wp-content\/uploads\/sites\/19\/2025\/03\/15MC-768x768.jpg 768w\" sizes=\"(max-width: 1080px) 100vw, 1080px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 Kick Off \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 SPU-Micro Credentials \u0e40\u0e14\u0e34\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2d\u0e19\u0e32\u0e04\u0e15 31 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2568 \u2013 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21 \u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21 Kick Off \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 SPU-Micro Credentials \u0e1c\u0e48\u0e32\u0e19\u0e23\u0e30\u0e1a\u0e1a ZOOM \u0e42\u0e14\u0e22\u0e21\u0e35\u0e15\u0e31\u0e27\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01 15 \u0e04\u0e13\u0e30\/\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19 \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e41\u0e1c\u0e19\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e17\u0e35\u0e21\u0e42\u0e04\u0e49\u0e0a \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e1e\u0e23\u0e30\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35 (KMUTT) \u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 Micro Credentials \u0e2b\u0e23\u0e37\u0e2d \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e23\u0e30\u0e22\u0e30\u0e2a\u0e31\u0e49\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e2d\u0e1a\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e41\u0e25\u0e30\u0e2a\u0e2d\u0e14\u0e23\u0e31\u0e1a\u0e01\u0e31\u0e1a\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e02\u0e2d\u0e07\u0e15\u0e25\u0e32\u0e14\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e19\u0e35\u0e49\u0e21\u0e35\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 6 \u0e40\u0e14\u0e37\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c\u0e41\u0e25\u0e30\u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23\u0e08\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e2a\u0e32\u0e02\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e28\u0e23\u0e35\u0e1b\u0e17\u0e38\u0e21\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32\u0e2a\u0e39\u0e48\u0e2d\u0e19\u0e32\u0e04\u0e15! #SPUMicroCredentials #MicroCredentials #LifelongLearning #EducationInnovation #SPU<\/p>\n","protected":false},"author":8,"featured_media":2774,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,2],"tags":[14,17,16,13],"class_list":["post-2772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-quality-education-sdg-4","category-2","tag-spu","tag-17","tag-16","tag-13"],"_links":{"self":[{"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/posts\/2772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/comments?post=2772"}],"version-history":[{"count":2,"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/posts\/2772\/revisions"}],"predecessor-version":[{"id":2777,"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/posts\/2772\/revisions\/2777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/media\/2774"}],"wp:attachment":[{"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/media?parent=2772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/categories?post=2772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.spu.ac.th\/department\/tlc\/wp-json\/wp\/v2\/tags?post=2772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}